{"id":1872,"date":"2020-10-07T11:01:00","date_gmt":"2020-10-07T09:01:00","guid":{"rendered":"http:\/\/blog.visitklagenfurt.at\/?p=1872"},"modified":"2022-10-17T15:32:47","modified_gmt":"2022-10-17T13:32:47","slug":"geheime-geschichten-ueber-klagenfurt","status":"publish","type":"post","link":"https:\/\/www.visitklagenfurt.at\/de\/blog\/sehenswertes-ausfluege\/geheime-geschichten-ueber-klagenfurt\/","title":{"rendered":"7 geheime Geschichten \u00fcber Klagenfurt die man wissen sollte"},"content":{"rendered":"\n<p>Die Geschichte ist in Klagenfurt allgegenw\u00e4rtig. Sie begegnet uns auf Schritt und Tritt. Sei es in Form von Geb\u00e4uden, Stra\u00dfen, H\u00e4usern, Denkm\u00e4lern oder Pl\u00e4tzen. Die Historie Klagenfurts kann man nachlesen. Aber die Geheimnisse mancher Orte, die Geschichten \u00fcber Gr\u00e4uel und Gewohnheiten fr\u00fcherer Bewohner, muss man sich erz\u00e4hlen lassen. Vieles von der historischen, faktischen Geschichte der K\u00e4rntner Landeshauptstadt zeigt sich dem Geschichtskundigen ohne viele Erkl\u00e4rungen. Aber hinter den Mauern, unter den Pl\u00e4tzen, im Dunkeln der Geschichte, verbergen sich die Geheimnisse und R\u00e4tsel, die menschlichen Schicksale und unglaublichen Begebenheiten.\u00a0Wir verraten euch sieben spannende und gleichzeitig erschreckende Geschichten \u00fcber Klagenfurt.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"663\" height=\"960\" data-id=\"1895\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/ID03-B_City-Arkarden_cTROe-Alte-Ansichten.jpg\" alt=\"Schwarz-wei\u00df Bild der Klagenfurter Innenstadt \" class=\"wp-image-1895\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/ID03-B_City-Arkarden_cTROe-Alte-Ansichten.jpg 663w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/ID03-B_City-Arkarden_cTROe-Alte-Ansichten-207x300.jpg 207w\" sizes=\"(max-width: 663px) 100vw, 663px\" \/><figcaption>(c) AAvK \/ TA\u00d6 <\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-alte-ansichten-und-mysteriose-orte\">Alte Ansichten und mysteri\u00f6se Orte<\/h2>\n\n\n\n<p>Ein paar dieser \u201eKlagenfurter Geschichten\u201d haben wir versucht, ans Licht zu holen. Wir haben nachgelesen, uns schlau gemacht und uns bei Kundigen umgeh\u00f6rt. <\/p>\n\n\n\n<p>Gefunden haben wir diese in Reinhold Gaspers <a href=\"https:\/\/www.heyn.at\/list?back=bc11b4addff73d4c1532c349ae52d5c9&amp;xid=31156818\" target=\"_blank\" rel=\"noreferrer noopener\">Klagenfurter Geschichte und Geschichten<\/a> B\u00e4nden, im Gespr\u00e4ch mit <a href=\"https:\/\/www.schlager-kaernten-guide.at\/\" target=\"_blank\" rel=\"noreferrer noopener\">Austria-Guide Susanne Schlager<\/a>, die im Rahmen der F\u00fchrung \u201eTatort Klagenfurt\u201c die blutr\u00fcnstigsten Ecken der Stadt abklappert. Und im Austausch mit Johannes Lebitsch, Mastermind hinter der beliebten Facebook-Gruppe <a href=\"https:\/\/www.facebook.com\/groups\/AlteAnsichtenVonKlagenfurt\/\" target=\"_blank\" rel=\"noreferrer noopener\">Alte Ansichten von Klagenfurt<\/a> und Autor der \u201eKlagenfurter Alltagsgeschichten\u201c in der Kronen Zeitung.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"644\" height=\"485\" data-id=\"1899\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/ID41-B_Stadtpfarrturm.jpg\" alt=\"Schwarz-Wei\u00df Bild der Klagenfurter Innenstadt mit Blick auf den Klagenfurter Dom\" class=\"wp-image-1899\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/ID41-B_Stadtpfarrturm.jpg 644w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/ID41-B_Stadtpfarrturm-300x226.jpg 300w\" sizes=\"(max-width: 644px) 100vw, 644px\" \/><figcaption>(c) AAvK \/ TA\u00d6 <\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-1-feuerbach-ein-tunnelsystem-unter-der-stadt\">1. Feuerbach: ein Tunnelsystem unter der Stadt<\/h2>\n\n\n\n<p>Viele Ger\u00fcchte ranken sich bis heute um den Feuerbach. Einem k\u00fcnstlichen Kanal unter der Stadt, der schon w\u00e4hrend des Baus der Stadtmauer angelegt wurde. Steht Klagenfurt heute tats\u00e4chlich auf einem Kanaltunnelsystem \u00e0 la \u201eDer Dritte Mann\u201c? Kann man diese unterirdischen Kan\u00e4le begehen?<\/p>\n\n\n\n<p>Ersteres: Ja. Zweiteres: Nein. Der Feuerbach, der einst in zwei oberirdischen Armen (Stadthaus-Ursulinengasse-Benediktinerplatz bzw. Theatergasse-Waaggasse-Bahnhofstra\u00dfe) die Innenstadt mit Wasser f\u00fcr den Eigengebrauch, f\u00fcr Pferde, zum Waschen und wohl auch f\u00fcr den Abtransport von G\u00fclle durchzog, vereinigte sich vor der heutigen Landesregierung wieder zu einem Bachbett.<\/p>\n\n\n\n<p>Von hier aus floss er Richtung Stadts\u00fcden weiter und m\u00fcndete schlie\u00dflich in die Sattnitz. Und ja, auch f\u00fcrs L\u00f6schen eventueller Feuersbr\u00fcnste war das Wasser gedacht. Allerdings wurde der Bach Mitte des 19. Jahrhunderts \u201eaus hygienischen Gr\u00fcnden\u201c tiefergelegt und als unterirdischer Kanal gef\u00fchrt, der nur \u00fcber ein paar Abg\u00e4nge im Zentrum erreichbar war. So blieb an gewissen Stellen \u2013 etwa dem Fluderbrunnen, der heute im Schillerpark steht \u2013 das Schwemmen der W\u00e4sche m\u00f6glich.<\/p>\n\n\n\n<p>Im S\u00fcden Klagenfurts ist noch heute ein Teilst\u00fcck seines Verlaufs oberirdisch &#8211; und f\u00fcr jeden, den es interessiert, ersichtlich: zwischen Kl\u00e4ranlage und dem Auenweg nahe dem Kalmusbad.\u00a0Wegen des Feuerbachs wurde die Bahnhofstra\u00dfe \u2013 hier mit der Kapuzinerkirche im Hintergrund &#8211; seinerzeit \u201eBreite-Bachstra\u00dfe\u201c genannt.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1875\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/1_Feuerbach_AlteAnsichtenvonKlagenfurt-1024x682.jpg\" alt=\"Schwarz-Wei\u00df Bild eines Platzes vor der Kirche in Klagenfurt \" class=\"wp-image-1875\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/1_Feuerbach_AlteAnsichtenvonKlagenfurt-1024x682.jpg 1024w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/1_Feuerbach_AlteAnsichtenvonKlagenfurt-300x200.jpg 300w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/1_Feuerbach_AlteAnsichtenvonKlagenfurt-768x512.jpg 768w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/1_Feuerbach_AlteAnsichtenvonKlagenfurt-1536x1024.jpg 1536w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/1_Feuerbach_AlteAnsichtenvonKlagenfurt.jpg 1772w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>(c) Alte Ansichten von Klagenfurt, Facebook<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-2-am-neuen-platz-stand-ein-galgen\">2. Am Neuen Platz stand ein Galgen<\/h2>\n\n\n\n<p>Bevor Anfang des 16. Jahrhunderts ein Feuer die Stadt in Schutt und Asche legte, waren Hinrichtungen sozusagen ein \u201czentrales Event\u201d. Der Galgen stand seinerzeit direkt am Neuen Platz, am heutigen Kreuzungspunkt zwischen Rathauseingang und Kramergasse.<\/p>\n\n\n\n<p>Nach dem Wiederaufbau der Stadt entschied man sich ab 1528 doch f\u00fcr einen Standort etwas au\u00dferhalb. Noch heute erinnert der <a href=\"https:\/\/de.wikipedia.org\/wiki\/Annabichl\" target=\"_blank\" rel=\"noreferrer noopener\">Galgenbichlweg<\/a> in Annabichl daran.<\/p>\n\n\n\n<p>Schlie\u00dflich wanderte die \u201eSt\u00e4tte des Grauens\u201c noch einmal weiter. Pikanterweise genau an jenen Ort an der Rosentalerstra\u00dfe, wo heute ein beliebtes amerikanisches Fast-Food-Restaurant f\u00fcr hohe Frequenz sorgt. Bei der letzten Hinrichtung im Jahr 1712 wurde ein 12-J\u00e4hriger gek\u00f6pft. F\u00fcrs Z\u00fcndeln in der Innenstadt.<\/p>\n\n\n\n<p>Am Standort des einstigen Galgens von Klagenfurt wurde Jahrhunderte sp\u00e4ter die Maria-Theresia-Statue gesetzt.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"662\" data-id=\"1876\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/2_NeuerPlatz1912_AlteAnsichtenvonKlagenfurt-1024x662.jpg\" alt=\"Altes Bild des Neuen Platzes in Klagenfurt\" class=\"wp-image-1876\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/2_NeuerPlatz1912_AlteAnsichtenvonKlagenfurt-1024x662.jpg 1024w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/2_NeuerPlatz1912_AlteAnsichtenvonKlagenfurt-300x194.jpg 300w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/2_NeuerPlatz1912_AlteAnsichtenvonKlagenfurt-768x497.jpg 768w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/2_NeuerPlatz1912_AlteAnsichtenvonKlagenfurt-1536x993.jpg 1536w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/2_NeuerPlatz1912_AlteAnsichtenvonKlagenfurt.jpg 1664w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>(c) Alte Ansichten von Klagenfurt, Facebook<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-3-wildes-treiben-im-lendhafen\">3. Wildes Treiben im Lendhafen<\/h2>\n\n\n\n<p>Heute ist es die meiste Zeit eher still im Lendhafen. Das war fr\u00fcher definitiv anders. Baumaterialien, Brennholz und P\u00f6rtschacher Marmor wurden am Wasserweg in die Stadt geschifft. Im Lendhafen wuselte es nur so. Es wurde t\u00e4glich hart gearbeitet. Und in den acht Brandweinstuben, die sich rundherum angesiedelt hatten, entsprechend ausgelassen gefeiert.<\/p>\n\n\n\n<p>Auch die Ausfl\u00fcgler kamen in den Lendhafen. Ab 1853 legte vom Lendhafen ein kleiner Schaufelraddampfer zweimal t\u00e4glich nach Velden ab. Der Andrang war riesig. Regelm\u00e4\u00dfig entstanden im Kampf um eine Fahrkarte Rempeleien und Schl\u00e4gereien.<\/p>\n\n\n\n<p>Um 1860 wurde ein neues Lastschiff getauft und seine Besatzung wusste diesen Anlass in den Hafenkneipen geb\u00fchrend zu feiern. Zu laut f\u00fcr manche Hafenanrainer. Der Gendarm, der daraufhin vorbei schaute, hatte gegen die betrunkene Horde aber keine Chance. Er landete in voller Uniform im Lendkanal und entkam nur knapp dem Ertrinken.<\/p>\n\n\n\n<p>Im Lendhafen herrschte fr\u00fcher reges Treiben. Im sp\u00e4ten 20. Jahrhundert noch wurde das Lendhafenfest gefeiert.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"991\" data-id=\"1877\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/3_Lendhafen_Lendhafenfest_AlteAnsichtenvonKlagenfurt-1024x991.jpg\" alt=\"Schwarz-Wei\u00df Bild des gut besuchten Lendhafens in Klagenfurt\" class=\"wp-image-1877\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/3_Lendhafen_Lendhafenfest_AlteAnsichtenvonKlagenfurt-1024x991.jpg 1024w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/3_Lendhafen_Lendhafenfest_AlteAnsichtenvonKlagenfurt-300x290.jpg 300w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/3_Lendhafen_Lendhafenfest_AlteAnsichtenvonKlagenfurt-768x743.jpg 768w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/3_Lendhafen_Lendhafenfest_AlteAnsichtenvonKlagenfurt-1536x1487.jpg 1536w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/3_Lendhafen_Lendhafenfest_AlteAnsichtenvonKlagenfurt.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>(c) Alte Ansichten von Klagenfurt, Facebook<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-4-kardinalplatz-die-zwielichtigste-ecke\">4. Kardinalplatz: die zwielichtigste Ecke <\/h2>\n\n\n\n<p>In fr\u00fchen Jahren hie\u00df der Kardinalplatz noch nicht nach dem kunstsinnigen und bergaffinen Kardinal Salm, der Anfang des 19. Jahrhunderts in Klagenfurt wirkte. In vielen alten Stadtpl\u00e4nen ist er als Viehplatz \u2013 wegen des hier stattfindenden Viehmarkts \u2013 zu finden. Teilweise hie\u00df er auch F\u00fcrsten- oder (in der NS-Zeit) Stuttgarterplatz.<\/p>\n\n\n\n<p>Jedenfalls war dies \u00fcber lange Zeit hindurch eine der rauheren Ecken der Stadt. Manche behaupten: das Rotlichtviertel. Bis in die Neuzeit herauf hielt sich jedenfalls die Adlerbar, eine Tanz- und Revuebar mit leicht bekleideten M\u00e4dchen, in der 1961 ein blutiger Mord an einem Gast begangen wurde. Die 19-j\u00e4hrige \u201eschwarze Susi\u201c, wie sie sp\u00e4ter von den Medien genannt wurde, schlug einem zudringlichen Verehrer mit dem St\u00f6ckelschuh den Sch\u00e4del ein &#8211; sehr romantisch\u2026&nbsp;<\/p>\n\n\n\n<p>In langen Phasen der Klagenfurter Geschichte galt der Kardinalsplatz als zwielichtiges Viertel der Stadt.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1878\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/4_Kardinalsplatzum1905_AlteAnsichtenvonKlagenfurt-1024x682.jpg\" alt=\"Altes Bild des Kardinalplatzes in Klagenfurt\" class=\"wp-image-1878\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/4_Kardinalsplatzum1905_AlteAnsichtenvonKlagenfurt-1024x682.jpg 1024w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/4_Kardinalsplatzum1905_AlteAnsichtenvonKlagenfurt-300x200.jpg 300w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/4_Kardinalsplatzum1905_AlteAnsichtenvonKlagenfurt-768x512.jpg 768w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/4_Kardinalsplatzum1905_AlteAnsichtenvonKlagenfurt-1536x1023.jpg 1536w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/4_Kardinalsplatzum1905_AlteAnsichtenvonKlagenfurt.jpg 1564w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>(c) Alte Ansichten von Klagenfurt, Facebook<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-5-ein-kafig-voller-narren-am-dr-arthur-lemisch-platz\">5. Ein K\u00e4fig voller Narren am Dr.-Arthur-Lemisch-Platz<\/h2>\n\n\n\n<p>Heute ist der Dr.-Arthur-Lemisch-Platz ein Idyll mit gro\u00dfem Brunnen in zentraler Lage. Vor ein paar hundert Jahren ging es allerdings wenig nobel her. Fr\u00fcher war hier nicht nur der Obstmarkt angesiedelt, sondern auch das sogenannte \u201eNarrenh\u00e4usl\u201c.<\/p>\n\n\n\n<p>Dabei handelte es sich um einen K\u00e4fig, in den jene Klagenfurter gesperrt wurden, die sich kleinere Vergehen und Moral\u00fcbertretungen geleistet hatten. Offenbar nahm im 16. Jahrhundert die Zahl der unehelichen Geburten so stark zu, dass der Rat ein Narrenh\u00e4usl f\u00fcr n\u00f6tig erachtete.<\/p>\n\n\n\n<p>Nach dem Motto \u201eWer sich erwischen l\u00e4sst, ist ein Narr\u201c wurden die Kleinkriminellen, Betr\u00fcger und viele ledig Schwangere hier \u00f6ffentlich zur Schau gestellt, verh\u00f6hnt, beschimpft, bespuckt, manchmal sogar mit dem Nachttopf \u00fcbergossen. Rauhe Sitten waren das. Gut, dass sie der Vergangenheit angeh\u00f6ren.<\/p>\n\n\n\n<p>Der Obstplatz \u2013 heute Arthur-Lemisch-Platz \u2013 war auch Standort des Klagenfurter Narrenh\u00e4usls.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"618\" data-id=\"1879\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/5_Obstplatz1_AlteAnsichtenvonKlagenfurt.jpg\" alt=\"Alte Schwraz-wei\u00df Postkarte des Dr.-Arthur-Lemisch-Platzes in Klagenfurt\" class=\"wp-image-1879\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/5_Obstplatz1_AlteAnsichtenvonKlagenfurt.jpg 960w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/5_Obstplatz1_AlteAnsichtenvonKlagenfurt-300x193.jpg 300w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/5_Obstplatz1_AlteAnsichtenvonKlagenfurt-768x494.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption>(c) Alte Ansichten von Klagenfurt, Facebook<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-6-im-geheimgang-isst-man-heute-asiatisch\">6. Im Geheimgang isst man heute asiatisch<\/h2>\n\n\n\n<p>Dass Klagenfurts Zentrum fr\u00fcher von einer massiven Stadtmauer umringt war, wei\u00df man. Der Zutritt in die Stadt war nur \u00fcber eines der vier gro\u00dfen Tore m\u00f6glich. Oder man kannte einen &#8211; meist verdeckten &#8211; Zugang zu einer der Poternen. Diese unterirdischen G\u00e4nge durch die Mauer dienten der Flucht, heimlichen Erkundungsg\u00e4ngen oder Gegenangriffen in Form von \u00fcberraschenden Ausf\u00e4llen. Drei der Klagenfurter Poternen sind bis in die Gegenwart noch (teilweise) vorhanden Eine ist f\u00fcr jedermann zug\u00e4nglich: Die Poterne am Kardinalplatz.<\/p>\n\n\n\n<p>Schon jahrelang ist sie ein Gastronomie-Standort, seit zwei Jahren kann man sich hier in der \u201eKyo Kitchen-Bar\u201c asiatische Spezialit\u00e4ten in historischem Ambiente servieren lassen &#8211; gem\u00fctlich, verborgen und ein bisschen mystisch.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-7-strandbad-klagenfurt-galt-als-sundenpfuhl\">7. Strandbad Klagenfurt galt als S\u00fcndenpfuhl<\/h2>\n\n\n\n<p>Im fr\u00fchen 20. Jahrhundert war es noch durchaus \u00fcblich, sich streng nach Geschlechtern getrennt im Sommer in die Fluten zu schmei\u00dfen. Sprich: Weiblein da, M\u00e4nnlein dort und meist durch einen hohen Bretterzaun getrennt.<\/p>\n\n\n\n<p>Als man 1923 mit der Planung des Klagenfurter Strandbades in der Ostbucht begann und durchsickerte, dass dort keine Trennung von badenden Frauen und M\u00e4nnern vorgesehen war, sorgte das f\u00fcr ordentlichen Unmut und Widerstand vonseiten der katholischen Kirche. Man bef\u00fcrchtete, dass das Strandbad zum S\u00fcndenpfuhl verkommen k\u00f6nnte! Er\u00f6ffnet wurde &#8211; allen frommen Sorgenfalten zum Trotz &#8211; im Jahre 1924. Sehr fortschrittlich. \ud83d\ude09&nbsp;<\/p>\n\n\n\n<p>Die katholische Kirche fand es 1923 gar nicht gut, dass im neuen Strandbad M\u00e4nnlein und Weiblein miteinander baden d\u00fcrfen.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-8 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"591\" height=\"406\" data-id=\"1882\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/7_Strandbad_AlteAnsichtenvonKlagenfurt.jpg\" alt=\"Alte Postkarte des Klagenfurter Strandbades im Sommer\" class=\"wp-image-1882\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/7_Strandbad_AlteAnsichtenvonKlagenfurt.jpg 591w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/7_Strandbad_AlteAnsichtenvonKlagenfurt-300x206.jpg 300w\" sizes=\"(max-width: 591px) 100vw, 591px\" \/><figcaption>(c) Alte Ansichten von Klagenfurt, Facebook<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-9 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"1897\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/Sonderbild-Seeleben2_cTROe-Alte-Ansichten-1024x768.jpg\" alt=\"Altes Bild des sehr gut besuchten Klagenfurter Strandbads im Sommer\" class=\"wp-image-1897\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/Sonderbild-Seeleben2_cTROe-Alte-Ansichten-1024x768.jpg 1024w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/Sonderbild-Seeleben2_cTROe-Alte-Ansichten-300x225.jpg 300w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/Sonderbild-Seeleben2_cTROe-Alte-Ansichten-768x576.jpg 768w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/Sonderbild-Seeleben2_cTROe-Alte-Ansichten-1536x1152.jpg 1536w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/Sonderbild-Seeleben2_cTROe-Alte-Ansichten.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>(c) AAvK \/ TA\u00d6<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-geheime-geschichte-erleben\">Geheime Geschichte erleben <\/h2>\n\n\n\n<p>Hinter den historischen Daten und Fakten verbergen sich viele Geschichten \u00fcber Klagenfurt und Geheimnisse der Stadt, die im Dunkeln der Vergangenheit fast verloren gingen. Einige engagierte Klagenfurter sammeln und recherchieren diese ungew\u00f6hnlichen Stories. Denn die Geschichte Klagenfurts ist mehr als Jahreszahlen und Herrschernamen. Ein Gesicht bekommt sie erst da, wo es auch in der Vergangenheit \u201cgemenschelt\u201d hat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gibt es unter Klagenfurt ein Tunnelsystem? Was passiert heute im einstigen Geheimgang durch die Stadtmauer? Und was hat der fr\u00fchere Galgen mit Fastfood zu tun? Wir haben die geschichtlichen Geheimnisse der Stadt zusammengefasst.<\/p>\n","protected":false},"author":8,"featured_media":1893,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[43,23],"class_list":["post-1872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sehenswertes-ausfluege","tag-stadtleben","tag-urlaub-und-freizeit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>7 geheime Geschichten \u00fcber Klagenfurt | visitklagenfurt<\/title>\n<meta name=\"description\" content=\"Gibt es unter der Stadt ein Tunnelsystem? Was passiert im Geheimgang durch die Stadtmauer? Wir haben 7 geheime Geschichten \u00fcber Klagenfurt!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.visitklagenfurt.at\/de\/blog\/sehenswertes-ausfluege\/geheime-geschichten-ueber-klagenfurt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7 geheime Geschichten \u00fcber Klagenfurt | visitklagenfurt\" \/>\n<meta property=\"og:description\" content=\"Gibt es unter der Stadt ein Tunnelsystem? Was passiert im Geheimgang durch die Stadtmauer? Wir haben 7 geheime Geschichten \u00fcber Klagenfurt!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visitklagenfurt.at\/de\/blog\/sehenswertes-ausfluege\/geheime-geschichten-ueber-klagenfurt\/\" \/>\n<meta property=\"og:site_name\" content=\"visitklagenfurt\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-07T09:01:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-17T13:32:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/ID12-B_Kiki-Kogelnig-Brunnen_cTROe-Alte-Ansichten.png\" \/>\n\t<meta property=\"og:image:width\" content=\"974\" \/>\n\t<meta property=\"og:image:height\" content=\"617\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Johanna Wohlfahrt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Johanna Wohlfahrt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/sehenswertes-ausfluege\\\/geheime-geschichten-ueber-klagenfurt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/sehenswertes-ausfluege\\\/geheime-geschichten-ueber-klagenfurt\\\/\"},\"author\":{\"name\":\"Johanna Wohlfahrt\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#\\\/schema\\\/person\\\/0a69a33beb43019798be20d9d9bbe303\"},\"headline\":\"7 geheime Geschichten \u00fcber Klagenfurt die man wissen sollte\",\"datePublished\":\"2020-10-07T09:01:00+00:00\",\"dateModified\":\"2022-10-17T13:32:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/sehenswertes-ausfluege\\\/geheime-geschichten-ueber-klagenfurt\\\/\"},\"wordCount\":1383,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/sehenswertes-ausfluege\\\/geheime-geschichten-ueber-klagenfurt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/ID12-B_Kiki-Kogelnig-Brunnen_cTROe-Alte-Ansichten.png\",\"keywords\":[\"Stadtleben\",\"Urlaub &amp; Freizeit\"],\"articleSection\":[\"Sehenswertes &amp; Ausfl\u00fcge\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/sehenswertes-ausfluege\\\/geheime-geschichten-ueber-klagenfurt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/sehenswertes-ausfluege\\\/geheime-geschichten-ueber-klagenfurt\\\/\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/sehenswertes-ausfluege\\\/geheime-geschichten-ueber-klagenfurt\\\/\",\"name\":\"7 geheime Geschichten \u00fcber Klagenfurt | visitklagenfurt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/sehenswertes-ausfluege\\\/geheime-geschichten-ueber-klagenfurt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/sehenswertes-ausfluege\\\/geheime-geschichten-ueber-klagenfurt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/ID12-B_Kiki-Kogelnig-Brunnen_cTROe-Alte-Ansichten.png\",\"datePublished\":\"2020-10-07T09:01:00+00:00\",\"dateModified\":\"2022-10-17T13:32:47+00:00\",\"description\":\"Gibt es unter der Stadt ein Tunnelsystem? Was passiert im Geheimgang durch die Stadtmauer? Wir haben 7 geheime Geschichten \u00fcber Klagenfurt!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/sehenswertes-ausfluege\\\/geheime-geschichten-ueber-klagenfurt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/sehenswertes-ausfluege\\\/geheime-geschichten-ueber-klagenfurt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/sehenswertes-ausfluege\\\/geheime-geschichten-ueber-klagenfurt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/ID12-B_Kiki-Kogelnig-Brunnen_cTROe-Alte-Ansichten.png\",\"contentUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/ID12-B_Kiki-Kogelnig-Brunnen_cTROe-Alte-Ansichten.png\",\"width\":974,\"height\":617,\"caption\":\"(c) AAvK \\\/ TA\u00d6\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/sehenswertes-ausfluege\\\/geheime-geschichten-ueber-klagenfurt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"visitklagenfurt\",\"item\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/category\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sehenswertes &amp; Ausfl\u00fcge\",\"item\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/category\\\/blog\\\/sehenswertes-ausfluege\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"7 geheime Geschichten \u00fcber Klagenfurt die man wissen sollte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/\",\"name\":\"visitklagenfurt\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#organization\",\"name\":\"Tourismus Region Klagenfurt am W\u00f6rthersee GmbH\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/DT_K_Klagenfurt_S_RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/DT_K_Klagenfurt_S_RGB.png\",\"width\":2082,\"height\":1511,\"caption\":\"Tourismus Region Klagenfurt am W\u00f6rthersee GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#\\\/schema\\\/person\\\/0a69a33beb43019798be20d9d9bbe303\",\"name\":\"Johanna Wohlfahrt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/johanna_wohlfahrt_512.jpg\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/johanna_wohlfahrt_512.jpg\",\"contentUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/johanna_wohlfahrt_512.jpg\",\"caption\":\"Johanna Wohlfahrt\"},\"description\":\"Hallo, Johanna Wohlfahrt mein Name. Studierte Germanistin, gelernte Printjournalistin, engagierte Bloggerin. 20 Jahre schon schreibe ich \u00fcber Reisen, Lifestyle und Trends f\u00fcr unterschiedliche Medien, Plattformen und Kan\u00e4le. Ich st\u00f6bere st\u00e4ndig nach Kuriosem, Herausragendem, nach der Story dahinter. Kaum ein Geheimtipp von K\u00e4rnten bis zur Adria, der mir verborgen bleibt. Schreibtischt\u00e4terin bin ich keine. Lieber mach ich mir selber ein Bild. Was gut ist, empfehle ich in meinen Texten gerne weiter. Alles andere bleibt au\u00dfen vor. Seit zwei Jahrzehnten ist Klagenfurt mein Habitat. Manchmal bin ich selbst erstaunt, wie sehr sich die Stadt in dieser Zeit entwickelt hat. Klagenfurt ist cool - und hier ist es nachzulesen.\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/author\\\/johanna_wohlfahrt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"7 geheime Geschichten \u00fcber Klagenfurt | visitklagenfurt","description":"Gibt es unter der Stadt ein Tunnelsystem? Was passiert im Geheimgang durch die Stadtmauer? Wir haben 7 geheime Geschichten \u00fcber Klagenfurt!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.visitklagenfurt.at\/de\/blog\/sehenswertes-ausfluege\/geheime-geschichten-ueber-klagenfurt\/","og_locale":"de_DE","og_type":"article","og_title":"7 geheime Geschichten \u00fcber Klagenfurt | visitklagenfurt","og_description":"Gibt es unter der Stadt ein Tunnelsystem? Was passiert im Geheimgang durch die Stadtmauer? Wir haben 7 geheime Geschichten \u00fcber Klagenfurt!","og_url":"https:\/\/www.visitklagenfurt.at\/de\/blog\/sehenswertes-ausfluege\/geheime-geschichten-ueber-klagenfurt\/","og_site_name":"visitklagenfurt","article_published_time":"2020-10-07T09:01:00+00:00","article_modified_time":"2022-10-17T13:32:47+00:00","og_image":[{"width":974,"height":617,"url":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/ID12-B_Kiki-Kogelnig-Brunnen_cTROe-Alte-Ansichten.png","type":"image\/png"}],"author":"Johanna Wohlfahrt","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Johanna Wohlfahrt","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/sehenswertes-ausfluege\/geheime-geschichten-ueber-klagenfurt\/#article","isPartOf":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/sehenswertes-ausfluege\/geheime-geschichten-ueber-klagenfurt\/"},"author":{"name":"Johanna Wohlfahrt","@id":"https:\/\/www.visitklagenfurt.at\/de\/#\/schema\/person\/0a69a33beb43019798be20d9d9bbe303"},"headline":"7 geheime Geschichten \u00fcber Klagenfurt die man wissen sollte","datePublished":"2020-10-07T09:01:00+00:00","dateModified":"2022-10-17T13:32:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/sehenswertes-ausfluege\/geheime-geschichten-ueber-klagenfurt\/"},"wordCount":1383,"commentCount":0,"publisher":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/#organization"},"image":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/sehenswertes-ausfluege\/geheime-geschichten-ueber-klagenfurt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/ID12-B_Kiki-Kogelnig-Brunnen_cTROe-Alte-Ansichten.png","keywords":["Stadtleben","Urlaub &amp; Freizeit"],"articleSection":["Sehenswertes &amp; Ausfl\u00fcge"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.visitklagenfurt.at\/de\/blog\/sehenswertes-ausfluege\/geheime-geschichten-ueber-klagenfurt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/sehenswertes-ausfluege\/geheime-geschichten-ueber-klagenfurt\/","url":"https:\/\/www.visitklagenfurt.at\/de\/blog\/sehenswertes-ausfluege\/geheime-geschichten-ueber-klagenfurt\/","name":"7 geheime Geschichten \u00fcber Klagenfurt | visitklagenfurt","isPartOf":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/sehenswertes-ausfluege\/geheime-geschichten-ueber-klagenfurt\/#primaryimage"},"image":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/sehenswertes-ausfluege\/geheime-geschichten-ueber-klagenfurt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/ID12-B_Kiki-Kogelnig-Brunnen_cTROe-Alte-Ansichten.png","datePublished":"2020-10-07T09:01:00+00:00","dateModified":"2022-10-17T13:32:47+00:00","description":"Gibt es unter der Stadt ein Tunnelsystem? Was passiert im Geheimgang durch die Stadtmauer? Wir haben 7 geheime Geschichten \u00fcber Klagenfurt!","breadcrumb":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/sehenswertes-ausfluege\/geheime-geschichten-ueber-klagenfurt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.visitklagenfurt.at\/de\/blog\/sehenswertes-ausfluege\/geheime-geschichten-ueber-klagenfurt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/sehenswertes-ausfluege\/geheime-geschichten-ueber-klagenfurt\/#primaryimage","url":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/ID12-B_Kiki-Kogelnig-Brunnen_cTROe-Alte-Ansichten.png","contentUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/10\/ID12-B_Kiki-Kogelnig-Brunnen_cTROe-Alte-Ansichten.png","width":974,"height":617,"caption":"(c) AAvK \/ TA\u00d6"},{"@type":"BreadcrumbList","@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/sehenswertes-ausfluege\/geheime-geschichten-ueber-klagenfurt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"visitklagenfurt","item":"https:\/\/www.visitklagenfurt.at\/de\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.visitklagenfurt.at\/de\/category\/blog\/"},{"@type":"ListItem","position":3,"name":"Sehenswertes &amp; Ausfl\u00fcge","item":"https:\/\/www.visitklagenfurt.at\/de\/category\/blog\/sehenswertes-ausfluege\/"},{"@type":"ListItem","position":4,"name":"7 geheime Geschichten \u00fcber Klagenfurt die man wissen sollte"}]},{"@type":"WebSite","@id":"https:\/\/www.visitklagenfurt.at\/de\/#website","url":"https:\/\/www.visitklagenfurt.at\/de\/","name":"visitklagenfurt","description":"","publisher":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.visitklagenfurt.at\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.visitklagenfurt.at\/de\/#organization","name":"Tourismus Region Klagenfurt am W\u00f6rthersee GmbH","url":"https:\/\/www.visitklagenfurt.at\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.visitklagenfurt.at\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/03\/DT_K_Klagenfurt_S_RGB.png","contentUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/03\/DT_K_Klagenfurt_S_RGB.png","width":2082,"height":1511,"caption":"Tourismus Region Klagenfurt am W\u00f6rthersee GmbH"},"image":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.visitklagenfurt.at\/de\/#\/schema\/person\/0a69a33beb43019798be20d9d9bbe303","name":"Johanna Wohlfahrt","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/07\/johanna_wohlfahrt_512.jpg","url":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/07\/johanna_wohlfahrt_512.jpg","contentUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/07\/johanna_wohlfahrt_512.jpg","caption":"Johanna Wohlfahrt"},"description":"Hallo, Johanna Wohlfahrt mein Name. Studierte Germanistin, gelernte Printjournalistin, engagierte Bloggerin. 20 Jahre schon schreibe ich \u00fcber Reisen, Lifestyle und Trends f\u00fcr unterschiedliche Medien, Plattformen und Kan\u00e4le. Ich st\u00f6bere st\u00e4ndig nach Kuriosem, Herausragendem, nach der Story dahinter. Kaum ein Geheimtipp von K\u00e4rnten bis zur Adria, der mir verborgen bleibt. Schreibtischt\u00e4terin bin ich keine. Lieber mach ich mir selber ein Bild. Was gut ist, empfehle ich in meinen Texten gerne weiter. Alles andere bleibt au\u00dfen vor. Seit zwei Jahrzehnten ist Klagenfurt mein Habitat. Manchmal bin ich selbst erstaunt, wie sehr sich die Stadt in dieser Zeit entwickelt hat. Klagenfurt ist cool - und hier ist es nachzulesen.","url":"https:\/\/www.visitklagenfurt.at\/de\/author\/johanna_wohlfahrt\/"}]}},"_links":{"self":[{"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/posts\/1872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/comments?post=1872"}],"version-history":[{"count":17,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/posts\/1872\/revisions"}],"predecessor-version":[{"id":45480,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/posts\/1872\/revisions\/45480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/media\/1893"}],"wp:attachment":[{"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/media?parent=1872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/categories?post=1872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/tags?post=1872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}