{"id":3510,"date":"2021-12-02T14:00:00","date_gmt":"2021-12-02T13:00:00","guid":{"rendered":"http:\/\/blog.visitklagenfurt.at\/?p=3510"},"modified":"2024-11-08T10:20:16","modified_gmt":"2024-11-08T09:20:16","slug":"diy-weihnachtsdeko-klagenfurt","status":"publish","type":"post","link":"https:\/\/www.visitklagenfurt.at\/de\/blog\/shopping-maerkte\/diy-weihnachtsdeko-klagenfurt\/","title":{"rendered":"Es weihnachtet in Klagenfurt: Weihnachtsdeko zum Kaufen und Selbermachen"},"content":{"rendered":"\n<p>Ob traditioneller Adventschmuck oder trendy Weihnachtsdeko \u2013 manche Leute gehen auf in der geduldigen Herstellung von einfallsreichen Dekorationen, andere setzen eher auf einen fr\u00f6hlichen Einkaufsbummel. F\u00fcr die verschiedensten Weihnachts- und Advent-Charaktere in Klagenfurt m\u00f6chten wir<strong> hier Anregungen<\/strong> vorstellen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Weihnachtsdeko f\u00fcr jeden Geschmack<\/h2>\n\n\n\n<p>Sch\u00f6ne Christbaumdeko mit Kugeln und Girlanden, kleine Holzfiguren von Tieren, Engerl in allen Variationen, Nussknackerfiguren und Wichtelm\u00e4nnchen. Sie alle machen sich sehr gut auf Fensterbrettern oder Regalen, besonders in Gr\u00fcppchen. Und hier gibt es diese Weihnachtsdeko zu kaufen. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-casa-viva\">Casa Viva<\/h3>\n\n\n\n<p>Wohnaccessoires von Casa Viva setzen fr\u00f6hliche und feierliche, erfrischende und <strong>ungew\u00f6hnliche Akzente <\/strong>\u2013 auch und besonders zu Weihnachten. Kostbare Stoffe, Teppiche, Kissen eignen sich als luxuri\u00f6se Geschenke. Kerzenhalter, schimmernde Gl\u00e4ser f\u00fcr Lichter und Weihnachtsschmuck gibt es im Country-Style wie auch in ultramodernem Design. Das Team am Alten Platz ber\u00e4t euch gerne.<\/p>\n\n\n\n<p>Adresse: Alter Platz 22, 9020 Klagenfurt am W\u00f6rthersee<br>Telefon: <a href=\"0043463516028\" target=\"_blank\" rel=\"noreferrer noopener\">+43 463 51 6028<\/a> <br>Webseite: <a href=\"http:\/\/ww.casa-viva.at\" target=\"_blank\" rel=\"noreferrer noopener\">www.casa-viva.at<\/a><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1007\" height=\"603\" data-id=\"31715\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/12\/c-Casa-Viva-rosa.jpg\" alt=\"Christbaumschmuck in beige, rosa und hellgr\u00fcn in Form von Blumen und gedrehten Kugeln mit Samtb\u00e4ndern von Casa Viva Einrichtungshaus in Klagenfurt\" class=\"wp-image-31715\"\/><figcaption class=\"wp-element-caption\">(c) Casa Viva <\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1001\" height=\"599\" data-id=\"31711\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/12\/c-Casa-Viva-Maedchen.jpg\" alt=\"Ein Christbaumanh\u00e4nger in Form eines M\u00e4dchens, das einen Stapel mit Geschenken tr\u00e4gt von Casa Viva in Klagenfurt\" class=\"wp-image-31711\"\/><figcaption class=\"wp-element-caption\">(c) Casa Viva<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Dise\u00f1o <\/h3>\n\n\n\n<p>In der Paulitschgasse d\u00fcrft ihr eure Homestory neu erfinden. Internationale Designerst\u00fccke aus ausgesuchten Naturmaterialien, M\u00f6bel, Leuchten und viele kleine, feine Wohn-Details im k\u00fchl-schlicht-<strong>todschicken Nordic Chic <\/strong>vermehren die Weihnachtsfreude.<\/p>\n\n\n\n<p>Auf 200 Quadratmetern findet wohl jede und jeder das gewisse Etwas abseits des Mainstreams. Sch\u00f6nes Beispiel: Muubs-Luna-Vasen in ihrer beeindruckenden Gr\u00f6\u00dfe, organischen Form und der ruhig naturfarbenen Mondlandschaft-Oberfl\u00e4che wirken wie Kunstwerke f\u00fcr sich selbst. Sie vermitteln gef\u00fcllt mit den passenden Naturalien weihnachtliches Feeling.<\/p>\n\n\n\n<p>Adresse: Paulitschgasse 11\/2, 9020 Klagenfurt<br>Telefon: <a href=\"0043463931813\" target=\"_blank\" rel=\"noreferrer noopener\">+43 463 931 813 <\/a><br>Webseite: <a href=\"http:\/\/www.diseno.at\" target=\"_blank\" rel=\"noreferrer noopener\">www.diseno.at<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Stilvolle Weihnachtsdeko f\u00fcr die Festtagstafel&nbsp;<\/h2>\n\n\n\n<p>Wie man seinen Tisch zu festlichen Angelegenheiten richtig deckt, haben wir bereits in unserem Blogbeitrag <a href=\"https:\/\/www.visitklagenfurt.at\/de\/blog\/essen-trinken\/tischdecken-nach-knigge\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tischlein deck dich<\/a> zusammengefasst. F\u00fcr die Ausstattung der weihnachtlichen Tafel gibt&#8217;s Abhilfe. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">WMF City Arkaden<\/h3>\n\n\n\n<p>Fehlen noch die passenden Longdrinkgl\u00e4ser f\u00fcr den Egg Nogg? Oder ein schickes Fisch-Besteck? Braucht ihr eine spezielle Motiv-Kuchenform? Gibt\u2019s heuer zum Fest vielleicht Asiatisches aus dem Wok? Bei WMF in den City-Arkaden bleiben keine W\u00fcnsche f\u00fcr den <strong>Bereich des Funktionellen und K\u00fcchenhandwerklichen<\/strong> unerf\u00fcllt, auch die Geschenkewelt bei WMF dreht sich nur um Genussmomente.<\/p>\n\n\n\n<p>Falls ihr euch schon einmal (wie ich gerade) gefragt habt: das K\u00fcrzel WMF steht \u00fcbrigens f\u00fcr W\u00fcrttembergische Metallwarenfabrik.<\/p>\n\n\n\n<p>Adresse: City-Arkaden, St. Veiter Ring 20, 9020 Klagenfurt am W\u00f6rthersee<br>Telefon: <a href=\"tel:0043463501993\">+43 463 501 993<\/a><br>Webseite: <a href=\"http:\/\/www.wmf.com\" target=\"_blank\" rel=\"noreferrer noopener\">www.wmf.com<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Blumige Weihnachtsdeko f\u00fcr drau\u00dfen &amp; drinnen<\/h2>\n\n\n\n<p>Das Haus ist erst so richtig festlich dekoriert, wenn auch Adventkranz, Weihnachtsstern und Mistelzweig an Position gebracht wurden. Hier gibt es definitiv kein Zuviel.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"889\" height=\"889\" data-id=\"31700\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Kranz-c-Blumen-Margit.png\" alt=\"Ein T\u00fcrkranz aus Naturmaterialien wie Tannenzapfen, Zweige, Hagebutten und roten Rosen von Blumen Margit\" class=\"wp-image-31700\"\/><figcaption class=\"wp-element-caption\">(c) Blumen Margit<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Advent und T\u00fcrkr\u00e4nze<\/h3>\n\n\n\n<p>Adventkr\u00e4nze sind die wohl beliebteste Weihnachtsdeko und sie selbst zu binden bringt besinnliche Stimmung. Au\u00dferdem trifft man haarscharf den eigenen Geschmack bei Kerzen, Schleifen, Kugeln, klassisch, l\u00e4ndlich oder elegant in Pastell. Auch T\u00fcrkr\u00e4nze in allen ihren Auspr\u00e4gungen versetzen jeden Besucher in gute Laune. Die Durchmesser reichen von bescheiden bis riesig. Sie zeigen sich je nach Vorliebe der Bewohner<strong> schlicht gewunden oder \u00fcppig geschm\u00fcckt <\/strong>(asymmetrisch best\u00fcckt ist en Vogue).<\/p>\n\n\n\n<p>Die Klagenfurter Profis haben f\u00fcr Kr\u00e4nze aller Art die passenden Materialien. Bei ihnen findet man Zweige wie tiefgr\u00fcne Fichte, duftende Tanne, fedrige Kiefer. Auch den \u201eUnterbau aus Bast, den ben\u00f6tigten Blumendraht und passende Accessoires kann man dort erwerben.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" data-id=\"3912\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Sonnenblume-Kranz-Naturmaterialien-c-Nicole-Hubmann.jpg\" alt=\"Weihnachtsdekoration, Weihnachten, Klagenfurt, Geschenkideen, Weihnachtsdeko, Floristen, Winterdekoration, Wintersaison, T\u00fcrkranz, Sonnenblume, Zimtstange, goldenes Herz, Tannenzapfen\" class=\"wp-image-3912\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Sonnenblume-Kranz-Naturmaterialien-c-Nicole-Hubmann.jpg 1000w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Sonnenblume-Kranz-Naturmaterialien-c-Nicole-Hubmann-300x200.jpg 300w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Sonnenblume-Kranz-Naturmaterialien-c-Nicole-Hubmann-768x511.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">Sonnenblume (c) Nicole Hubmann<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"960\" data-id=\"3885\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Pucher-Kranz-mit-Schleife-natur-c_Blumen-Pucher.jpg\" alt=\"Weihnachtslicher T\u00fcrkranz mit wei\u00dfer Schlaufe aus dem Blumenladen Blumen Pucher in Klagenfurt \" class=\"wp-image-3885\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Pucher-Kranz-mit-Schleife-natur-c_Blumen-Pucher.jpg 960w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Pucher-Kranz-mit-Schleife-natur-c_Blumen-Pucher-300x300.jpg 300w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Pucher-Kranz-mit-Schleife-natur-c_Blumen-Pucher-150x150.jpg 150w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Pucher-Kranz-mit-Schleife-natur-c_Blumen-Pucher-768x768.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption class=\"wp-element-caption\">Blumen Pucher (c) Nicole Hubmann<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Weihnachtssterne <\/h3>\n\n\n\n<p>Poinsettien, besser bekannt als Weihnachtssterne, in vielen Farben kann man nie genug haben. Die Menge macht\u2019s, je mehr desto weihnachtlicher. Bei mir stehen sie in den Wochen vor Weihnachten sogar im Bad. Der Weihnachtsstern gl\u00fcht in tiefem Rot, bezaubert in weichen Rosat\u00f6nen oder besticht in fr\u00f6hlichem Wei\u00df. Eine adventlichere Pflanze gibt es irgendwie nicht.<\/p>\n\n\n\n<p>Hier ein paar gute Tipps, damit die farbigen Bl\u00e4tter lange frisch bleiben. Die Weihnachtssterne sind <strong>ziemlich k\u00e4lteempfindlich<\/strong>, also aufpassen, dass sie nicht zu viel kalte Luft und Zug abkriegen. Sie <strong>m\u00f6gen helle Standorte<\/strong>, ohne dass direkte Sonne draufknallt. Gie\u00dfen mit zimmertemperiertem Wasser.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-festliche-strausse\">Festliche Str\u00e4u\u00dfe<\/h3>\n\n\n\n<p>Neben Weihnachtssternen machen auch Weihnachtskakteen, Orchideen, Kamelien und nat\u00fcrlich fantasievolle Str\u00e4u\u00dfe und Gestecke in den weihnachtlichen Farben Rot und Gr\u00fcn, mit oder ohne vergoldete Bl\u00e4tter und Rispen die Wohnung noch einladender und strahlender. An Stiegenabs\u00e4tzen h\u00fcbsch:<strong> Str\u00e4u\u00dfe aus \u00c4sten und Zweigen nach Ikebana-Art<\/strong> in t\u00f6nernen Gef\u00e4\u00dfen oder in metallenen K\u00fcbelchen. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"1000\" data-id=\"3926\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/c-Blumen-Brommer-13.jpg\" alt=\"Weihnachtssterne in einem Blumenladen in Klagenfurt\" class=\"wp-image-3926\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/c-Blumen-Brommer-13.jpg 750w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/c-Blumen-Brommer-13-225x300.jpg 225w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><figcaption class=\"wp-element-caption\">(c) Blumen Brommer<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" data-id=\"3879\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Matzner-Amaryllis-Blumenstrauss-mit-Kugel-c-Nicole-Hubmann.jpg\" alt=\"Weihnachtsdekoration, Weihnachten, Klagenfurt, Geschenkideen, Weihnachtsdeko, Floristen, Winterdekoration, Wintersaison, Amaryllis, rote Blumen, Floristen, Weihnachtsgesteck, Blumen Matzner\" class=\"wp-image-3879\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Matzner-Amaryllis-Blumenstrauss-mit-Kugel-c-Nicole-Hubmann.jpg 1000w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Matzner-Amaryllis-Blumenstrauss-mit-Kugel-c-Nicole-Hubmann-300x200.jpg 300w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Matzner-Amaryllis-Blumenstrauss-mit-Kugel-c-Nicole-Hubmann-768x511.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">Blumen Matzner (c) Nicole Hubmann<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"960\" data-id=\"3861\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/c_Blumen-Pucher-Bluete-Zweig-Weihnachten.jpg\" alt=\"Blumen Pucher Klagenfurt Weihnachtsdekoration Schneerosen Weihnachtsgeschenk Winterblumen\" class=\"wp-image-3861\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/c_Blumen-Pucher-Bluete-Zweig-Weihnachten.jpg 960w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/c_Blumen-Pucher-Bluete-Zweig-Weihnachten-300x300.jpg 300w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/c_Blumen-Pucher-Bluete-Zweig-Weihnachten-150x150.jpg 150w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/c_Blumen-Pucher-Bluete-Zweig-Weihnachten-768x768.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption class=\"wp-element-caption\">Blumen Pucher (c) Blumen Pucher<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p>Unglaubliche Wirkung erzielen ebenso Str\u00e4u\u00dfe frischer Blumen, die in die Jahreszeit passen. Von prachtvollen, repr\u00e4sentativen <strong>Amaryllisst\u00e4ngeln<\/strong> mit ihren prallen Knospen, die zu \u00fcppigen Bl\u00fcten aufspringen, braucht man nur wenige, um eine Vase zu f\u00fcllen und die Stimmung zu heben. <\/p>\n\n\n\n<p><strong>Weihnachtskakteen <\/strong>in passenden Gef\u00e4\u00dfen bl\u00fchen aus Leibeskr\u00e4ften um diese Zeit. Anemonen in Rot, Lilablau und Wei\u00df mit den schwarzen \u00c4uglein in ihrer Mitte sehen als Sorte allein ebenso festlich aus wie gemischt mit den \u00c4sten der japanischen Stechpalme (nur die roten Kugerl, ohne spitze Bl\u00e4tter). Selbstverst\u00e4ndlich darf man sich von den Fachleuten auch spezielle opulente oder asketische Str\u00e4u\u00dfe zusammenstellen lassen, die alle weihnachtlichen St\u00fcckerl spielen.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" data-id=\"3934\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Pogatschnig-Gesteckt-Kugel-Aeste-Orangen-c-Nicole-Hubmann-15.jpg\" alt=\"Weihnachtlich dekorierte Blumengestecke \" class=\"wp-image-3934\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Pogatschnig-Gesteckt-Kugel-Aeste-Orangen-c-Nicole-Hubmann-15.jpg 1000w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Pogatschnig-Gesteckt-Kugel-Aeste-Orangen-c-Nicole-Hubmann-15-300x200.jpg 300w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Pogatschnig-Gesteckt-Kugel-Aeste-Orangen-c-Nicole-Hubmann-15-768x511.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">Blumen Pogatschnig (c) Klamag<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mistelzweige <\/h3>\n\n\n\n<p>F\u00fcr Singles ein unverzichtbares weihnachtliches Accessoire. Schlie\u00dflich ist es offiziell erlaubt, den heimlich Angebeteten, die im Verborgenen Verehrte irgendwie unter die Mistel zu schubsen und gnadenlos zu k\u00fcssen. <\/p>\n\n\n\n<p>Die kugeligen oder struppigen Bl\u00e4ttergebilde mit ihren durchsichtigen Beeren h\u00e4ngen dekorativ vom Luster oder \u00fcber T\u00fcrrahmen (praktisch, irgendwann muss da jeder durch). Wundersch\u00f6n weihnachtlich wirken die <strong>Mistel an breiten roten Leinen- oder Samtb\u00e4ndern mit riesiger Schleife<\/strong> \u2013 die Blumenh\u00e4ndler in Klagenfurt zaubern das gerne hin.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-klagenfurter-blumen-fachgeschafte\">Klagenfurter Blumen-Fachgesch\u00e4fte <\/h3>\n\n\n\n<p>F\u00fcr all diese Bl\u00fcten- und Pflanzen-Weihnachtsboten, f\u00fcr fachgerechte Beratung, f\u00fcr noch mehr Ideen stehen die G\u00e4rtner und Floristen in Klagenfurt bereit. Hier eine Adress-Auswahl in alphabetischer Reihenfolge:<\/p>\n\n\n\n<p><strong>Blumen Brommer<\/strong><br>Adresse: Luegerstrasse 27, 9020 Klagenfurt am W\u00f6rthersee<br>Telefon: <a href=\"0043463226000\" target=\"_blank\" rel=\"noreferrer noopener\">+43 463 226 000<\/a><br>Webseite: <a href=\"https:\/\/www.brommer.at\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.brommer.at<\/a><\/p>\n\n\n\n<p><strong>Blumen Daniela Matzner<\/strong><br>Adresse: Villacher Strasse 1A, 9020 Klagenfurt am W\u00f6rthersee<br>Telefon: <a href=\"0043463513286\" target=\"_blank\" rel=\"noreferrer noopener\">+43 463 513 286<\/a><br>Webseite: <a href=\"https:\/\/www.blumenmatzner.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.blumenmatzner.com<\/a><\/p>\n\n\n\n<p><strong>Blumen Margit<\/strong><br>Adresse: Rudolfsbahng\u00fcrtel 80, 9020 Klagenfurt am W\u00f6rthersee <br>Telefon: <a href=\"0043463330489\" target=\"_blank\" rel=\"noreferrer noopener\">+43 463 33 04 89<\/a><br>Webseite:<a href=\"https:\/\/www.instagram.com\/blumen_margit\/\" target=\"_blank\" rel=\"noreferrer noopener\">  Blumen Margit auf Instagram<\/a><\/p>\n\n\n\n<p><strong>Blumen Pogatschnig<\/strong><br>Adresse: Radetzkystrasse 38, 9020 Klagenfurt am W\u00f6rthersee <br>Telefon: <a href=\"0043463330489\" target=\"_blank\" rel=\"noreferrer noopener\">+43 463 390 81 12&nbsp;<\/a><br>Webseite: <a href=\"https:\/\/www.blumen-klagenfurt.at\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.blumen-klagenfurt.at<\/a><\/p>\n\n\n\n<p><strong>Blumen Pucher<\/strong><br>Adresse: Karfreitstrasse 15, 9020 Klagenfurt am W\u00f6rthersee<br>Telefon: <a href=\"004346356861\" target=\"_blank\" rel=\"noreferrer noopener\">+43 463 56861<\/a><br>Webseite: <a href=\"https:\/\/www.blumen-pucher.at\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.blumen-pucher.a<\/a><\/p>\n\n\n\n<p><strong>Gartenwelt Kropfitsch<\/strong><br>Adresse: St. Veiter Strasse 84, 9020 Klagenfurt am W\u00f6rthersee<br>Telefon: <a href=\"0043463513517\" target=\"_blank\" rel=\"noreferrer noopener\">+43 463 513 517<\/a><br>Webseite: <a href=\"https:\/\/www.gartenwelt-kropfitsch.at\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.gartenwelt-kropfitsch.at<\/a><\/p>\n\n\n\n<p><strong>Sonnenblume<\/strong><br>Adresse: Radetzkystra\u00dfe 8, 9020 Klagenfurt am W\u00f6rthersee<br>Telefon:&nbsp;<a href=\"0043463302190\" target=\"_blank\" rel=\"noreferrer noopener\">+43 463 302190<\/a><br>Website: <a href=\"http:\/\/www.sonnen-blume.at\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.sonnen-blume.at<\/a><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" data-id=\"3931\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Matzner-Stechpalme-Apfel-c-Nicole-Hubmann.jpg\" alt=\"Weihnachtliche Blumendeko aus einem der Blumen-Fachgesch\u00e4fte in Klagenfurt\" class=\"wp-image-3931\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Matzner-Stechpalme-Apfel-c-Nicole-Hubmann.jpg 1000w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Matzner-Stechpalme-Apfel-c-Nicole-Hubmann-300x200.jpg 300w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Matzner-Stechpalme-Apfel-c-Nicole-Hubmann-768x511.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">Blumen Matzner (c) Klamag<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">W\u00e4rmende D\u00fcfte, Kl\u00e4nge &amp; Geschm\u00e4cker<\/h2>\n\n\n\n<p>Es gibt nichts Sch\u00f6neres, wenn das ganzen Haus weihnachtlich durftet und s\u00fc\u00dfe Kl\u00e4nge die Seele zum Baumeln bringen. Auch S\u00fc\u00dfes zum Anschauen und Schlemmen darf im Advent nicht fehlen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sonnentor<\/h3>\n\n\n\n<p>LiebhaberInnen von <strong>k\u00f6stlich-festlichen Raum-D\u00fcften<\/strong> werden bei Sonnentor f\u00fcndig. \u00c4therische \u00d6le mit Namen wie <em>O Du Duftende (Geschenkset), Winternacht, S\u00fc\u00dfe Orange, Schutzengel, Wintersonne, Kiefernadel <\/em>sowie spiritueller Weihrauch und viele mehr verbreiten ihre himmlischen Aromen in der Wohnung. Die dazugeh\u00f6rigen Duftsteine kann man sich hier auch aussuchen, dazu Duftlampen und Diffusoren.<\/p>\n\n\n\n<p>Die au\u00dferordentlich romantisch gestalteten <strong>Sch\u00e4chtelchen mit jahreszeitlich passenden Keks-Kreationen<\/strong> sind nette Mitbringsel im Advent. Ebenso gibt es viele h\u00fcbsch verpackte <strong>winterliche Teekreatione<\/strong>n (sehr herzig die Tee- oder Gew\u00fcrz-Adventkalender) und Gl\u00fchwein-Punsch-Spezereimischungen. Alles in Bio-Qualit\u00e4t selbstverst\u00e4ndlich, ohne k\u00fcnstliche Zus\u00e4tze, wie es dem hehren Motto des Waldviertler Gr\u00fcnders Johannes Gutmann entspricht.<\/p>\n\n\n\n<p>Adresse: Wiener Gasse 5, 9020 Klagenfurt am W\u00f6rthersee<br>Telefon: <a href=\"0043463276002\" target=\"_blank\" rel=\"noreferrer noopener\">+43 463 276 002<\/a><br>Webseite: <a href=\"http:\/\/www.sonnentor.com\" target=\"_blank\" rel=\"noreferrer noopener\">www.sonnentor.com<\/a><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-8 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" data-id=\"4466\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/01\/Sonnentor-c-Arnold-Poeschl_Blog.jpg\" alt=\"Sonnentor Klagenfurt, Wienergasse, Teeregal, Teetasse, Tee, 9020, Klagenfurt am W\u00f6rthersee, Klagenfurttee, Winterfitness, Winter, Innenstadt Klagenfurt\" class=\"wp-image-4466\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/01\/Sonnentor-c-Arnold-Poeschl_Blog.jpg 1000w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/01\/Sonnentor-c-Arnold-Poeschl_Blog-300x200.jpg 300w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/01\/Sonnentor-c-Arnold-Poeschl_Blog-768x511.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">Sonnetor (c) Arnold P\u00f6schl<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mandala <\/h3>\n\n\n\n<p>Leise Kl\u00e4nge, sanfte D\u00fcfte. <strong>Viel orientalisch<\/strong> Inspiriertes, aber auch <strong>heimisches R\u00e4ucherwerk<\/strong> und alle n\u00f6tigen Ger\u00e4te und Utensilien sowie die praktische Beratung und Anleitung offeriert das Team von Mandala. Der wei\u00dfe Salbei zum Beispiel gilt als besonders feines der aktivierenden, kl\u00e4renden Rauch-Mittel und f\u00fchrt ganz schnell zur Weisheit. Warum nicht versuchen?<\/p>\n\n\n\n<p>Viele der angebotenen Waren stammen aus <strong>Klagenfurter Eigenproduktion,<\/strong> da gibt es wundersch\u00f6n vielfarbige Kerzen, holzgeschnitzte Figuren und Anh\u00e4nger, Kr\u00e4uter-Mischungen und R\u00e4ucherpf\u00e4nnchen.<\/p>\n\n\n\n<p>Adresse: Alter Platz 4, 9020 Klagenfurt am W\u00f6rthersee<br>Telefon: <a href=\"tel:0463501834\" target=\"_blank\" rel=\"noreferrer noopener\">+<\/a><a href=\"tel:0043463501834\">43 463 5<\/a><a href=\"0043463501834\" target=\"_blank\" rel=\"noreferrer noopener\">0<\/a><a href=\"tel:0043463501834\"> 18 34<\/a><br>Webseite: <a href=\"http:\/\/www.mandala.earth\" target=\"_blank\" rel=\"noreferrer noopener\">www.mandala.earth<\/a><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-9 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" data-id=\"31727\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/12\/ra\u0308ucher-1920w-c-Mandala.jpg\" alt=\"Eine Auswahl an R\u00e4ucherst\u00e4bchen bei Mandala in Klagenfurt\" class=\"wp-image-31727\"\/><figcaption class=\"wp-element-caption\">(c) Mandala<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">DIY-Duft aus Orangen und Nelken als Weihnachtsdekoration<\/h2>\n\n\n\n<p>Ein Weihnachtsdeko-Tipp noch zum Schluss: In meiner lang verflossenen Kindheit habe ich meine zahllosen Tanten beschenkt mit Gew\u00fcrznelken-gespickten Orangen. Ein Geduldsspiel, denn die Nagerl m\u00fcssen dicht an dicht sitzen \u2013 aber schon w\u00e4hrend der Daumen zermarternden M\u00fche erg\u00f6tzt der k\u00f6stliche Duft der Fr\u00fcchte und Gew\u00fcrze die Familie. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-10 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" data-id=\"3894\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Orange-mit-Nelken-aromatischer-Duft-c-Nicole-Hubmann.jpg\" alt=\"Zwei frische Orangen mit Nelken verziert sorgen f\u00fcr einen weihnachtlichen Duft zuhause\" class=\"wp-image-3894\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Orange-mit-Nelken-aromatischer-Duft-c-Nicole-Hubmann.jpg 1000w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Orange-mit-Nelken-aromatischer-Duft-c-Nicole-Hubmann-300x200.jpg 300w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Orange-mit-Nelken-aromatischer-Duft-c-Nicole-Hubmann-768x511.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">(c) Klamag<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-facebook  wp-block-social-link\"><a href=\"https:\/\/www.facebook.com\/klagenfurtcity\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12 2C6.5 2 2 6.5 2 12c0 5 3.7 9.1 8.4 9.9v-7H7.9V12h2.5V9.8c0-2.5 1.5-3.9 3.8-3.9 1.1 0 2.2.2 2.2.2v2.5h-1.3c-1.2 0-1.6.8-1.6 1.6V12h2.8l-.4 2.9h-2.3v7C18.3 21.1 22 17 22 12c0-5.5-4.5-10-10-10z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Facebook<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-instagram  wp-block-social-link\"><a href=\"https:\/\/www.instagram.com\/klagenfurt_city\/\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12,4.622c2.403,0,2.688,0.009,3.637,0.052c0.877,0.04,1.354,0.187,1.671,0.31c0.42,0.163,0.72,0.358,1.035,0.673 c0.315,0.315,0.51,0.615,0.673,1.035c0.123,0.317,0.27,0.794,0.31,1.671c0.043,0.949,0.052,1.234,0.052,3.637 s-0.009,2.688-0.052,3.637c-0.04,0.877-0.187,1.354-0.31,1.671c-0.163,0.42-0.358,0.72-0.673,1.035 c-0.315,0.315-0.615,0.51-1.035,0.673c-0.317,0.123-0.794,0.27-1.671,0.31c-0.949,0.043-1.233,0.052-3.637,0.052 s-2.688-0.009-3.637-0.052c-0.877-0.04-1.354-0.187-1.671-0.31c-0.42-0.163-0.72-0.358-1.035-0.673 c-0.315-0.315-0.51-0.615-0.673-1.035c-0.123-0.317-0.27-0.794-0.31-1.671C4.631,14.688,4.622,14.403,4.622,12 s0.009-2.688,0.052-3.637c0.04-0.877,0.187-1.354,0.31-1.671c0.163-0.42,0.358-0.72,0.673-1.035 c0.315-0.315,0.615-0.51,1.035-0.673c0.317-0.123,0.794-0.27,1.671-0.31C9.312,4.631,9.597,4.622,12,4.622 M12,3 C9.556,3,9.249,3.01,8.289,3.054C7.331,3.098,6.677,3.25,6.105,3.472C5.513,3.702,5.011,4.01,4.511,4.511 c-0.5,0.5-0.808,1.002-1.038,1.594C3.25,6.677,3.098,7.331,3.054,8.289C3.01,9.249,3,9.556,3,12c0,2.444,0.01,2.751,0.054,3.711 c0.044,0.958,0.196,1.612,0.418,2.185c0.23,0.592,0.538,1.094,1.038,1.594c0.5,0.5,1.002,0.808,1.594,1.038 c0.572,0.222,1.227,0.375,2.185,0.418C9.249,20.99,9.556,21,12,21s2.751-0.01,3.711-0.054c0.958-0.044,1.612-0.196,2.185-0.418 c0.592-0.23,1.094-0.538,1.594-1.038c0.5-0.5,0.808-1.002,1.038-1.594c0.222-0.572,0.375-1.227,0.418-2.185 C20.99,14.751,21,14.444,21,12s-0.01-2.751-0.054-3.711c-0.044-0.958-0.196-1.612-0.418-2.185c-0.23-0.592-0.538-1.094-1.038-1.594 c-0.5-0.5-1.002-0.808-1.594-1.038c-0.572-0.222-1.227-0.375-2.185-0.418C14.751,3.01,14.444,3,12,3L12,3z M12,7.378 c-2.552,0-4.622,2.069-4.622,4.622S9.448,16.622,12,16.622s4.622-2.069,4.622-4.622S14.552,7.378,12,7.378z M12,15 c-1.657,0-3-1.343-3-3s1.343-3,3-3s3,1.343,3,3S13.657,15,12,15z M16.804,6.116c-0.596,0-1.08,0.484-1.08,1.08 s0.484,1.08,1.08,1.08c0.596,0,1.08-0.484,1.08-1.08S17.401,6.116,16.804,6.116z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Instagram<\/span><\/a><\/li><\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was lieben wir in unseren wenig christlichen Zeiten eigentlich noch immer so an der Vorweihnachtszeit? Tannentassen, Mistelzweig, Kerzen, Goldschimmer und Sternenglanz. Der nahende Winter triggert die Sehnsucht nach Geborgenheit, nach Lichtern, Duft und W\u00e4rme.<\/p>\n","protected":false},"author":12,"featured_media":3879,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[10,43,55],"class_list":["post-3510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shopping-maerkte","tag-shopping","tag-stadtleben","tag-winter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weihnachtsdeko zum Kaufen &amp; Selbermachen: DIY | visitklagenfurt<\/title>\n<meta name=\"description\" content=\"Ob traditioneller Adventschmuck oder trendy Weihnachtsdeko: In Klagenfurt kann man sch\u00f6ne Weihnachtsdeko kaufen oder selber machen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.visitklagenfurt.at\/de\/blog\/shopping-maerkte\/diy-weihnachtsdeko-klagenfurt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weihnachtsdeko zum Kaufen &amp; Selbermachen: DIY | visitklagenfurt\" \/>\n<meta property=\"og:description\" content=\"Ob traditioneller Adventschmuck oder trendy Weihnachtsdeko: In Klagenfurt kann man sch\u00f6ne Weihnachtsdeko kaufen oder selber machen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visitklagenfurt.at\/de\/blog\/shopping-maerkte\/diy-weihnachtsdeko-klagenfurt\/\" \/>\n<meta property=\"og:site_name\" content=\"visitklagenfurt\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-02T13:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-08T09:20:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Matzner-Amaryllis-Blumenstrauss-mit-Kugel-c-Nicole-Hubmann.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anna-Maria Haider\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna-Maria Haider\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/shopping-maerkte\\\/diy-weihnachtsdeko-klagenfurt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/shopping-maerkte\\\/diy-weihnachtsdeko-klagenfurt\\\/\"},\"author\":{\"name\":\"Anna-Maria Haider\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#\\\/schema\\\/person\\\/fbc9f55c3b447ed37410a6e7cfb4a622\"},\"headline\":\"Es weihnachtet in Klagenfurt: Weihnachtsdeko zum Kaufen und Selbermachen\",\"datePublished\":\"2021-12-02T13:00:00+00:00\",\"dateModified\":\"2024-11-08T09:20:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/shopping-maerkte\\\/diy-weihnachtsdeko-klagenfurt\\\/\"},\"wordCount\":1415,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/shopping-maerkte\\\/diy-weihnachtsdeko-klagenfurt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Weihnachtsdekoration-Blumen-Matzner-Amaryllis-Blumenstrauss-mit-Kugel-c-Nicole-Hubmann.jpg\",\"keywords\":[\"Shopping\",\"Stadtleben\",\"Winter\"],\"articleSection\":[\"Shopping &amp; M\u00e4rkte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/shopping-maerkte\\\/diy-weihnachtsdeko-klagenfurt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/shopping-maerkte\\\/diy-weihnachtsdeko-klagenfurt\\\/\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/shopping-maerkte\\\/diy-weihnachtsdeko-klagenfurt\\\/\",\"name\":\"Weihnachtsdeko zum Kaufen & Selbermachen: DIY | visitklagenfurt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/shopping-maerkte\\\/diy-weihnachtsdeko-klagenfurt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/shopping-maerkte\\\/diy-weihnachtsdeko-klagenfurt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Weihnachtsdekoration-Blumen-Matzner-Amaryllis-Blumenstrauss-mit-Kugel-c-Nicole-Hubmann.jpg\",\"datePublished\":\"2021-12-02T13:00:00+00:00\",\"dateModified\":\"2024-11-08T09:20:16+00:00\",\"description\":\"Ob traditioneller Adventschmuck oder trendy Weihnachtsdeko: In Klagenfurt kann man sch\u00f6ne Weihnachtsdeko kaufen oder selber machen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/shopping-maerkte\\\/diy-weihnachtsdeko-klagenfurt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/shopping-maerkte\\\/diy-weihnachtsdeko-klagenfurt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/shopping-maerkte\\\/diy-weihnachtsdeko-klagenfurt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Weihnachtsdekoration-Blumen-Matzner-Amaryllis-Blumenstrauss-mit-Kugel-c-Nicole-Hubmann.jpg\",\"contentUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Weihnachtsdekoration-Blumen-Matzner-Amaryllis-Blumenstrauss-mit-Kugel-c-Nicole-Hubmann.jpg\",\"width\":1000,\"height\":666,\"caption\":\"Blumen Matzner (c) Nicole Hubmann\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/shopping-maerkte\\\/diy-weihnachtsdeko-klagenfurt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"visitklagenfurt\",\"item\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/category\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Shopping &amp; M\u00e4rkte\",\"item\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/category\\\/blog\\\/shopping-maerkte\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Es weihnachtet in Klagenfurt: Weihnachtsdeko zum Kaufen und Selbermachen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/\",\"name\":\"visitklagenfurt\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#organization\",\"name\":\"Tourismus Region Klagenfurt am W\u00f6rthersee GmbH\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/DT_K_Klagenfurt_S_RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/DT_K_Klagenfurt_S_RGB.png\",\"width\":2082,\"height\":1511,\"caption\":\"Tourismus Region Klagenfurt am W\u00f6rthersee GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#\\\/schema\\\/person\\\/fbc9f55c3b447ed37410a6e7cfb4a622\",\"name\":\"Anna-Maria Haider\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/anna.jpg\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/anna.jpg\",\"contentUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/anna.jpg\",\"caption\":\"Anna-Maria Haider\"},\"description\":\"Wenn auch seit Jahrzehnten mit Lebensmittelpunkt in der Stadt Salzburg und famili\u00e4rer \u201eAu\u00dfenstelle\u201c im Waldviertel bin ich als geb\u00fcrtige Klagenfurterin ein gl\u00fchender K\u00e4rnten-Fan geblieben. Meine bevorzugten Themen finde ich im Gebiet der Kunst und Kultur, wobei mir Entdeckungen - ob historischen oder zeitgen\u00f6ssischen Wesens - abseits des Mainstreams sehr am Herzen liegen. Dabei kommen mir Erfahrungen aus meiner Zeit als textende Kunsthistorikerin in verschiedenen Galerien und die abwechslungsreiche T\u00e4tigkeit als freie Journalistin f\u00fcr Tageszeitung und Magazin zugute. Meine Heimatstadt Klagenfurt und ihre inspirierende Umgebung empfinde ich als seltene, wohltuende Synthese aus lebendig Urbanem und kontemplativ-kostbarer Natur. Eine Position, die meine drei erwachsenen S\u00f6hne teilen, sie sind sehr stolz auf ihre K\u00e4rntner Wurzeln.\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/author\\\/anna_maria_haider\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weihnachtsdeko zum Kaufen & Selbermachen: DIY | visitklagenfurt","description":"Ob traditioneller Adventschmuck oder trendy Weihnachtsdeko: In Klagenfurt kann man sch\u00f6ne Weihnachtsdeko kaufen oder selber machen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.visitklagenfurt.at\/de\/blog\/shopping-maerkte\/diy-weihnachtsdeko-klagenfurt\/","og_locale":"de_DE","og_type":"article","og_title":"Weihnachtsdeko zum Kaufen & Selbermachen: DIY | visitklagenfurt","og_description":"Ob traditioneller Adventschmuck oder trendy Weihnachtsdeko: In Klagenfurt kann man sch\u00f6ne Weihnachtsdeko kaufen oder selber machen.","og_url":"https:\/\/www.visitklagenfurt.at\/de\/blog\/shopping-maerkte\/diy-weihnachtsdeko-klagenfurt\/","og_site_name":"visitklagenfurt","article_published_time":"2021-12-02T13:00:00+00:00","article_modified_time":"2024-11-08T09:20:16+00:00","og_image":[{"width":1000,"height":666,"url":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Matzner-Amaryllis-Blumenstrauss-mit-Kugel-c-Nicole-Hubmann.jpg","type":"image\/jpeg"}],"author":"Anna-Maria Haider","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Anna-Maria Haider","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/shopping-maerkte\/diy-weihnachtsdeko-klagenfurt\/#article","isPartOf":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/shopping-maerkte\/diy-weihnachtsdeko-klagenfurt\/"},"author":{"name":"Anna-Maria Haider","@id":"https:\/\/www.visitklagenfurt.at\/de\/#\/schema\/person\/fbc9f55c3b447ed37410a6e7cfb4a622"},"headline":"Es weihnachtet in Klagenfurt: Weihnachtsdeko zum Kaufen und Selbermachen","datePublished":"2021-12-02T13:00:00+00:00","dateModified":"2024-11-08T09:20:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/shopping-maerkte\/diy-weihnachtsdeko-klagenfurt\/"},"wordCount":1415,"commentCount":0,"publisher":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/#organization"},"image":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/shopping-maerkte\/diy-weihnachtsdeko-klagenfurt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Matzner-Amaryllis-Blumenstrauss-mit-Kugel-c-Nicole-Hubmann.jpg","keywords":["Shopping","Stadtleben","Winter"],"articleSection":["Shopping &amp; M\u00e4rkte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.visitklagenfurt.at\/de\/blog\/shopping-maerkte\/diy-weihnachtsdeko-klagenfurt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/shopping-maerkte\/diy-weihnachtsdeko-klagenfurt\/","url":"https:\/\/www.visitklagenfurt.at\/de\/blog\/shopping-maerkte\/diy-weihnachtsdeko-klagenfurt\/","name":"Weihnachtsdeko zum Kaufen & Selbermachen: DIY | visitklagenfurt","isPartOf":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/shopping-maerkte\/diy-weihnachtsdeko-klagenfurt\/#primaryimage"},"image":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/shopping-maerkte\/diy-weihnachtsdeko-klagenfurt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Matzner-Amaryllis-Blumenstrauss-mit-Kugel-c-Nicole-Hubmann.jpg","datePublished":"2021-12-02T13:00:00+00:00","dateModified":"2024-11-08T09:20:16+00:00","description":"Ob traditioneller Adventschmuck oder trendy Weihnachtsdeko: In Klagenfurt kann man sch\u00f6ne Weihnachtsdeko kaufen oder selber machen.","breadcrumb":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/shopping-maerkte\/diy-weihnachtsdeko-klagenfurt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.visitklagenfurt.at\/de\/blog\/shopping-maerkte\/diy-weihnachtsdeko-klagenfurt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/shopping-maerkte\/diy-weihnachtsdeko-klagenfurt\/#primaryimage","url":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Matzner-Amaryllis-Blumenstrauss-mit-Kugel-c-Nicole-Hubmann.jpg","contentUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/12\/Weihnachtsdekoration-Blumen-Matzner-Amaryllis-Blumenstrauss-mit-Kugel-c-Nicole-Hubmann.jpg","width":1000,"height":666,"caption":"Blumen Matzner (c) Nicole Hubmann"},{"@type":"BreadcrumbList","@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/shopping-maerkte\/diy-weihnachtsdeko-klagenfurt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"visitklagenfurt","item":"https:\/\/www.visitklagenfurt.at\/de\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.visitklagenfurt.at\/de\/category\/blog\/"},{"@type":"ListItem","position":3,"name":"Shopping &amp; M\u00e4rkte","item":"https:\/\/www.visitklagenfurt.at\/de\/category\/blog\/shopping-maerkte\/"},{"@type":"ListItem","position":4,"name":"Es weihnachtet in Klagenfurt: Weihnachtsdeko zum Kaufen und Selbermachen"}]},{"@type":"WebSite","@id":"https:\/\/www.visitklagenfurt.at\/de\/#website","url":"https:\/\/www.visitklagenfurt.at\/de\/","name":"visitklagenfurt","description":"","publisher":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.visitklagenfurt.at\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.visitklagenfurt.at\/de\/#organization","name":"Tourismus Region Klagenfurt am W\u00f6rthersee GmbH","url":"https:\/\/www.visitklagenfurt.at\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.visitklagenfurt.at\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/03\/DT_K_Klagenfurt_S_RGB.png","contentUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/03\/DT_K_Klagenfurt_S_RGB.png","width":2082,"height":1511,"caption":"Tourismus Region Klagenfurt am W\u00f6rthersee GmbH"},"image":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.visitklagenfurt.at\/de\/#\/schema\/person\/fbc9f55c3b447ed37410a6e7cfb4a622","name":"Anna-Maria Haider","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/09\/anna.jpg","url":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/09\/anna.jpg","contentUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/09\/anna.jpg","caption":"Anna-Maria Haider"},"description":"Wenn auch seit Jahrzehnten mit Lebensmittelpunkt in der Stadt Salzburg und famili\u00e4rer \u201eAu\u00dfenstelle\u201c im Waldviertel bin ich als geb\u00fcrtige Klagenfurterin ein gl\u00fchender K\u00e4rnten-Fan geblieben. Meine bevorzugten Themen finde ich im Gebiet der Kunst und Kultur, wobei mir Entdeckungen - ob historischen oder zeitgen\u00f6ssischen Wesens - abseits des Mainstreams sehr am Herzen liegen. Dabei kommen mir Erfahrungen aus meiner Zeit als textende Kunsthistorikerin in verschiedenen Galerien und die abwechslungsreiche T\u00e4tigkeit als freie Journalistin f\u00fcr Tageszeitung und Magazin zugute. Meine Heimatstadt Klagenfurt und ihre inspirierende Umgebung empfinde ich als seltene, wohltuende Synthese aus lebendig Urbanem und kontemplativ-kostbarer Natur. Eine Position, die meine drei erwachsenen S\u00f6hne teilen, sie sind sehr stolz auf ihre K\u00e4rntner Wurzeln.","url":"https:\/\/www.visitklagenfurt.at\/de\/author\/anna_maria_haider\/"}]}},"_links":{"self":[{"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/posts\/3510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/comments?post=3510"}],"version-history":[{"count":41,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/posts\/3510\/revisions"}],"predecessor-version":[{"id":71315,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/posts\/3510\/revisions\/71315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/media\/3879"}],"wp:attachment":[{"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/media?parent=3510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/categories?post=3510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/tags?post=3510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}