{"id":39187,"date":"2022-06-27T10:00:00","date_gmt":"2022-06-27T08:00:00","guid":{"rendered":"https:\/\/www.visitklagenfurt.at\/?p=39187"},"modified":"2022-08-17T15:24:50","modified_gmt":"2022-08-17T13:24:50","slug":"bademoeglichkeiten-abseits-des-woerthersees","status":"publish","type":"post","link":"https:\/\/www.visitklagenfurt.at\/de\/blog\/urlaub-freizeit\/bademoeglichkeiten-abseits-des-woerthersees\/","title":{"rendered":"Badem\u00f6glichkeiten abseits des W\u00f6rthersees"},"content":{"rendered":"\n<p>Schattig, frisch und angenehm. So zeigen sich die Lieblingsbadeorte der Klagenfurter von ihrer besten Seite ohne sich wie eine \u00d6lsardine f\u00fchlen zu m\u00fcssen. Hier brutzeln maximal die W\u00fcrstel am Grill. Ab geht\u2019s zu den coolen Badem\u00f6glichkeiten fernab des W\u00f6rthersees. Und reinspringen kann man trotzdem ins kalte Nass. Abk\u00fchlung garantiert!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-sattnitz\">Sattnitz <\/h2>\n\n\n\n<p>Gewusst, dass der W\u00f6rthersee einen k\u00fcnstlichen Abfluss hat? Die Sattnitz ist mit ihren 9 Kilometern der einzige Abfluss des wohl bekanntesten Sees \u00d6sterreichs. Der slowenische Name verr\u00e4t die Bedeutung: &#8222;Jezernica&#8220;, sprich \u201e<strong>Fluss vom See<\/strong>\u201c. Aber eigentlich hei\u00dft sie ja &#8222;Glanfurt&#8220;, aber die Klagenfurter nennen sie &#8222;Sattnitz&#8220;, wortgleich einem Gebirgszug.<\/p>\n\n\n\n<p>Die &#8222;Sattnitz&#8220; beginnt in der <a href=\"https:\/\/www.visitklagenfurt.at\/de\/woerthersee-und-umgebung\/woerthersee-ostbucht\/\">Klagenfurter Ostbucht<\/a>. S\u00fcdlich der Halbinsel Maria Loretto, im schilfreichen, naturbelassenen Teil , verl\u00e4uft sie Richtung Osten und ist mit zahlreichen kleinen Boots-, Bade- und Wochenendh\u00e4uschen an beiden Ufern best\u00fcckt. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1440\" height=\"1799\" data-id=\"39191\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/06\/e6832710d93378432c31ca0a68370f6b.jpg\" alt=\"\" class=\"wp-image-39191\"\/><figcaption>(c) IG, dominik_fessl<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p>Die ersten 800 Meter windet sich die Sattnitz in leichten Kurven durch eine naturbelassene <strong>Auenlandschaft<\/strong>. Erst ab der Seeschleuse (bei der Querung durch die W\u00f6rthersee-S\u00fcdufer-Stra\u00dfe) ist sie tiefer gelegt. Parallel zum Fluss verl\u00e4uft ein <strong>Fu\u00df- und Radfahrweg<\/strong>. Er begleitet den Fluss ein gutes St\u00fcck und endet erst an der Waidmannsdorfer Stra\u00dfe.<\/p>\n\n\n\n<p>An der Strecke gibt es in kleinen Parks viele M\u00f6glichkeiten zum Einstieg und der Erfrischung \u2013 saftige <strong>Wiesen und Spielpl\u00e4tze<\/strong> laden zum Stehenbleiben und Verweilen ein. Die kostenlosen Gr\u00fcnanlagen mit Gew\u00e4sserzugang sind zwar keine offiziellen Badepl\u00e4tze, werden aber an hei\u00dfen Sommertagen von vielen Menschen genutzt, die Abk\u00fchlung suchen.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"692\" height=\"864\" data-id=\"39372\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/06\/sattnitz1.png\" alt=\"\" class=\"wp-image-39372\"\/><figcaption>(c) IG, dominik_fessl<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Freizeitparks an der Sattnitz <\/h3>\n\n\n\n<p>Beliebt ist der &#8222;<strong>Freizeitpark Sattnitz Waidmannsdorf<\/strong>&#8220; nahe dem W\u00f6rthersee Stadion. Der St. Ruprechter Sattnitzpark Ost \u2013 liebevoll \u201edas Volksbad\u201c genannt \u2013 an der Schr\u00f6dingerstrasse nahe dem bekannten Wirtschaftsgeb\u00e4ude der Fruchtsaftmarke Pago war sogar einmal das alte Klagenfurter Strandbad.<\/p>\n\n\n\n<p>Das Kleinod ist ein beliebter Ort f\u00fcr Hundebesitzer, Fischer und Freizeitbegeisterte. Auf \u00fcber 6.000 Quadratmeter entfaltet sich eine eigene Freizeitwelt bei <strong>freiem Eintritt<\/strong>. Hier genie\u00dfen alle das s\u00fcdliche Flair abseits des klassischen Tourismus am W\u00f6rthersee. Neben einem Kinderspielplatz und \u00f6ffentlichen Grillpl\u00e4tzen stehen den Erholungssuchenden Toiletten und Umkleidekabinen gratis zur Verf\u00fcgung.<\/p>\n\n\n\n<p>Nach einem sch\u00f6nen Badetag geht es dann auf einen Abstecher in das nahe gelegene <a href=\"https:\/\/sattnitzstueberl.eatbu.com\/?lang=de\">Sattnitzst\u00fcberl <\/a>zu k\u00fchlen Getr\u00e4nken und einer z\u00fcnftigen Jause. Auch beim <a href=\"http:\/\/zum-weinlaender.at\/\">Weinl\u00e4nder<\/a> direkt an der Sattnitz l\u00e4sst es sich kulinarisch ganz gem\u00fctlich bei tollem Service genie\u00dfen. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1642\" height=\"1095\" data-id=\"1161\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/08\/natur_sattnitz_sommer_c-derhandler_6-web1.jpg\" alt=\"Radfahren entlang der Sattnitz\" class=\"wp-image-1161\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/08\/natur_sattnitz_sommer_c-derhandler_6-web1.jpg 1642w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/08\/natur_sattnitz_sommer_c-derhandler_6-web1-300x200.jpg 300w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/08\/natur_sattnitz_sommer_c-derhandler_6-web1-1024x683.jpg 1024w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/08\/natur_sattnitz_sommer_c-derhandler_6-web1-768x512.jpg 768w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/08\/natur_sattnitz_sommer_c-derhandler_6-web1-1536x1024.jpg 1536w\" sizes=\"(max-width: 1642px) 100vw, 1642px\" \/><figcaption>(c) Wolfgang Handler<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-waidischbach\">Waidischbach<\/h2>\n\n\n\n<p>Abseits der Massen sich richtig gut erfrischen. Das kann der &#8222;Waidischbach&#8220;. Natur pur mit einer Menge Kies und herrlichem Flair erwartet die Besucher hier. Dazu braucht es nur eine 15-min\u00fctige Autofahrt von Klagenfurt <strong>Richtung Ferlach<\/strong>. Schwupps &#8211; \u00fcber die gro\u00dfe Autobr\u00fccke wird die Drau gequert. Von dort gibt es viele Wege zum beliebten Ausflugsziel. Eine Stra\u00dfe f\u00fchrt \u00fcber den beliebten <a href=\"https:\/\/www.gasthof-plasch.at\/\">Gasthof Plasch<\/a>, der vor der Heimreise immer eine kulinarische St\u00e4rkung Wert ist.<\/p>\n\n\n\n<p>Am &#8222;Waidischbach&#8220; wird vor allem gechillt und gegrillt. Das W\u00fcrstel am Stecken und ein Bier reichen, um gl\u00fccklich zu sein. Den Rest erledigt das Rauschen des Wassers. Manche entdecken das Treibholzsammeln, andere jagen ihre Modellautos die Kiesberge hoch. Ein Juwel, das alle friedlich sein l\u00e4sst. Entspannt ist man nach so einem Tag im S\u00fcden von Klagenfurt allemal!<\/p>\n\n\n\n<p>Alle nehmen Mitgebrachtes wieder mit \u2013 der Umwelt zuliebe! Etwa 300 Meter vor dem M\u00fcndungsbereich des Baches in die Drau befindet sich eine Fischaufstiegshilfe. Hier lie\u00df der &#8222;<strong>Fischereiverein Thymallus<\/strong>&#8220; eine Ruheoase mit Einblick in die Fischwelt der Alpenb\u00e4che entstehen. Naturliebhaber entdecken kleine T\u00fcmpel, k\u00f6nnen die Fische beobachten. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1350\" data-id=\"39377\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/06\/15ae2022ec5d434993e9c197ae75f1fa.jpg\" alt=\"\" class=\"wp-image-39377\"\/><figcaption>(c) IG, marychinling<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Ressnigteich<\/h2>\n\n\n\n<p>Und ganz nah dran, etwas \u00f6stlicher vom &#8222;Waidischbach&#8220; ist der &#8222;<strong>Ressnigteich<\/strong>&#8222;. Auch eine Empfehlung \u2013 vor allem f\u00fcr <strong>Hundehalter<\/strong>! Hier gibt es eigene Areale und die Tiere d\u00fcrfen am Nordufer ins Wasser. Am S\u00fcdufer sitzen die Fischer und warten, bis etwas am Haken zupft. Sehr idyllisch sind die einsamen Momente am einzigen Steg, wenn sich alles rundherum leert und man in den Sonnenuntergang blickt.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1350\" data-id=\"39435\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/06\/fbc64a6853c40c113e864feea9477059.jpg\" alt=\"\" class=\"wp-image-39435\"\/><figcaption>(c) IG, _j.u.n.i_<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Linsendorfer See<\/h2>\n\n\n\n<p>Der Linsendorfer See liegt auf einem Landstreifen zwischen der Drau und dem Sattnitzh\u00fcgel. Dieser idyllische kleine See mit einer Fl\u00e4che von drei Hektar ist im alten Draubett angelegt und war fr\u00fcher einmal eine Flussschleife. Eine naturbelassene Liegewiese und das Baden bei freiem Eintritt machen ihn zum Geheimtipp. Ein idealer Ort f\u00fcr einen Sprung ins Wasser nach dem Radfahren oder f\u00fcr Ruhesuchende. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1263\" data-id=\"39213\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/06\/a83c825bce0a8812649dec63a168edcc.jpg\" alt=\"\" class=\"wp-image-39213\"\/><figcaption>(c) IG, petxos<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-wildensteiner-wasserfall\">Wildensteiner Wasserfall<\/h2>\n\n\n\n<p>Die wenigsten wissen, dass es gleich in der N\u00e4he von Klagenfurt einen Wasserfall gibt. \u00dcberrascht? Und dann ist es auch noch der <strong>h\u00f6chste freifallende Wasserfall Europas<\/strong>!<\/p>\n\n\n\n<p>Mit einer Fallh\u00f6he von erstaunlichen <strong>54 Metern<\/strong> rauscht der &#8222;Wildensteiner Wasserfall&#8220; in die Tiefe. Unterhalb des Hochobir-Gipfels gelegen, ist der Anstieg zum Wasserfall (ca. 20 Minuten) in den ersten beiden Drittel harmlos. \u00dcber Serpentinen geht es zum erfrischenden Ausflugsziel. Das letzte Drittel schaffen aber auch unge\u00fcbte Spazierg\u00e4nger.<\/p>\n\n\n\n<p>Je n\u00e4her man gelangt, desto lauter wird das Rauschen des Wassers \u2013 die Vorfreude, einen Blick auf das Naturdenkmal zu erhaschen, steigt mit jedem Schritt. Geschafft! Nun ist es erfrischend k\u00fchl. Eine Wohltat!<\/p>\n\n\n\n<p>Auf der Plattform beim &#8222;Wildensteiner Wasserfall &#8222;stehen Sitzgelegenheiten bereit. Hier kann man sich ausruhen und den Anblick auf den Wasserfall genie\u00dfen. Einheimische wissen: Die Erfrischung am Fu\u00dfe des Berges ist in Bedienung beim idyllischen <a href=\"https:\/\/www.gasthofzenkl.at\/\">Gasthof Zenkl<\/a> umso freundlicher.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"18836\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/04\/2047.jpg\" alt=\"K\u00e4rntens sch\u00f6nste Ausflugsziele wie Wildensteiner Wasserfall\" class=\"wp-image-18836\"\/><figcaption>(c) KW, Gert Steinthaler\t<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-kalmusbad\">Kalmusbad<\/h2>\n\n\n\n<p>Das &#8222;Kalmusbad&#8220; am s\u00fcd\u00f6stlichen Rand von Klagenfurt versteckt sich zwischen mannshohen Maisfeldern in <strong>Ebenthal<\/strong>. Schattig parken ist unter gro\u00dfen B\u00e4umen ideal m\u00f6glich und erinnert ein wenig an Campen.&nbsp;<\/p>\n\n\n\n<p>Seit 1932 ist das Kalmusbad in Familienbesitz. Elisabeth Ehart betreibt <strong>in dritter Generation<\/strong> das gem\u00fctliche Gasthaus. Mit ihren drei erwachsenen Kindern steht auch schon die vierte Generation in den Startl\u00f6chern. Die Familie tischt nahezu alle Lebensmittel aus eigener Produktion auf. Kein Wunder: Haben sie doch einen Bauernhof und eine Schwarzbrotb\u00e4ckerei. Unbedingt die Brettljause kosten!<\/p>\n\n\n\n<p>Die \u00fcberaus <strong>kinderfreundliche Anlage<\/strong> entpuppt sich als lauschiger Geheimtipp, wenn es ums Baden geht. Erwachsene zahlen \u20ac 1,50, Kinder ab drei Jahren \u20ac 0,50&nbsp;Eintritt ins Bad. Kinder wie Eltern lieben den \u00fcberschaubaren Freiraum, der Gegenstrom der Sattnitz spornt schwimmsichere Kinder zum Tollen im Wasser an. Hier kann man in Ruhe baden und sich erholen.<\/p>\n\n\n\n<p>Den Namen hat das urige Pl\u00e4tzchen \u00fcbrigens von der &#8222;<strong>Sumpfpflanze Kalmus<\/strong>&#8222;, der vielf\u00e4ltige Heilkr\u00e4fte zugeschrieben werden. So gilt Kalmus in der asiatischen Medizin und bei indigenen V\u00f6lkern Nordamerikas als kr\u00e4ftigend etwa bei Magen-Darm-Beschwerden.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-8 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"720\" data-id=\"39195\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/06\/8f61fee22780f0f1781377f1cd7dc2ac.jpg\" alt=\"\" class=\"wp-image-39195\"\/><figcaption>(c) IG, Pege78<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-pure-erfrischung-rund-um-klagenfurt-am-worthersee\">Pure Erfrischung rund um Klagenfurt am W\u00f6rthersee<\/h2>\n\n\n\n<p>Badem\u00f6glichkeiten gibt es viele, wenn es um den bekanntesten See \u00d6sterreichs geht. Doch abseits des W\u00f6rthersees wissen oft nur die Einheimischen, wo man sich erfrischen kann. Die Hot Spots wie Kalmusbad &amp; Co. sind f\u00fcr jedermann da.<\/p>\n\n\n\n<p>Beim n\u00e4chsten Mal einfach Klagenfurt von einer ganz anderen Seite kennenlernen. Mit Turnschuhen und Badehose zum Wildensteiner Wasserfall. Nicht nur seine hohe Luftfeuchtigkeit erfrischt erhitzte Gem\u00fcter. Auch der k\u00fchle Waidischbach und die Sattnitz ziehen zahlreiche Menschen an, die es lieber uriger beim Baden haben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Klagenfurt kann so viel mehr als nur W\u00f6rthersee! Wenn die Tage immer hei\u00dfer werden, sehnt man sich nach k\u00fchleren Outdoor-Pl\u00e4tzen. Da kommen die wilden, naturbelassenen Orte gerade recht, um der Hitze zu entfliehen. Und \u00fcberf\u00fcllt sind sie auch nicht. Noch nicht! Begleitet uns auf eine Entdeckungstour abseits der Badem\u00f6glichkeiten am W\u00f6rthersees.<\/p>\n","protected":false},"author":5,"featured_media":39195,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[5],"class_list":["post-39187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urlaub-freizeit","tag-sommer"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Baden abseits des W\u00f6rthersees: Sattnitz, Kalmusbad, etc. | visitklagenfurt<\/title>\n<meta name=\"description\" content=\"Tipps f\u00fcr Wasserratten abseits des W\u00f6rthersees. Wilde Einstiege und erfrischende Geheimtipps aus Klagenfurt. Abk\u00fchlung garantiert!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.visitklagenfurt.at\/de\/blog\/urlaub-freizeit\/bademoeglichkeiten-abseits-des-woerthersees\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baden abseits des W\u00f6rthersees: Sattnitz, Kalmusbad, etc. | visitklagenfurt\" \/>\n<meta property=\"og:description\" content=\"Tipps f\u00fcr Wasserratten abseits des W\u00f6rthersees. Wilde Einstiege und erfrischende Geheimtipps aus Klagenfurt. Abk\u00fchlung garantiert!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visitklagenfurt.at\/de\/blog\/urlaub-freizeit\/bademoeglichkeiten-abseits-des-woerthersees\/\" \/>\n<meta property=\"og:site_name\" content=\"visitklagenfurt\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-27T08:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-17T13:24:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/06\/8f61fee22780f0f1781377f1cd7dc2ac.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Isabella Sch\u00f6ndorfer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Isabella Sch\u00f6ndorfer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/urlaub-freizeit\\\/bademoeglichkeiten-abseits-des-woerthersees\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/urlaub-freizeit\\\/bademoeglichkeiten-abseits-des-woerthersees\\\/\"},\"author\":{\"name\":\"Isabella Sch\u00f6ndorfer\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#\\\/schema\\\/person\\\/ff6e2ff5da4943f8ce5aa0eb7608c20a\"},\"headline\":\"Badem\u00f6glichkeiten abseits des W\u00f6rthersees\",\"datePublished\":\"2022-06-27T08:00:00+00:00\",\"dateModified\":\"2022-08-17T13:24:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/urlaub-freizeit\\\/bademoeglichkeiten-abseits-des-woerthersees\\\/\"},\"wordCount\":1191,\"publisher\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/urlaub-freizeit\\\/bademoeglichkeiten-abseits-des-woerthersees\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/8f61fee22780f0f1781377f1cd7dc2ac.jpg\",\"keywords\":[\"Sommer\"],\"articleSection\":[\"Urlaub &amp; Freizeit\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/urlaub-freizeit\\\/bademoeglichkeiten-abseits-des-woerthersees\\\/\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/urlaub-freizeit\\\/bademoeglichkeiten-abseits-des-woerthersees\\\/\",\"name\":\"Baden abseits des W\u00f6rthersees: Sattnitz, Kalmusbad, etc. | visitklagenfurt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/urlaub-freizeit\\\/bademoeglichkeiten-abseits-des-woerthersees\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/urlaub-freizeit\\\/bademoeglichkeiten-abseits-des-woerthersees\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/8f61fee22780f0f1781377f1cd7dc2ac.jpg\",\"datePublished\":\"2022-06-27T08:00:00+00:00\",\"dateModified\":\"2022-08-17T13:24:50+00:00\",\"description\":\"Tipps f\u00fcr Wasserratten abseits des W\u00f6rthersees. Wilde Einstiege und erfrischende Geheimtipps aus Klagenfurt. Abk\u00fchlung garantiert!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/urlaub-freizeit\\\/bademoeglichkeiten-abseits-des-woerthersees\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/urlaub-freizeit\\\/bademoeglichkeiten-abseits-des-woerthersees\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/urlaub-freizeit\\\/bademoeglichkeiten-abseits-des-woerthersees\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/8f61fee22780f0f1781377f1cd7dc2ac.jpg\",\"contentUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/8f61fee22780f0f1781377f1cd7dc2ac.jpg\",\"width\":1080,\"height\":720,\"caption\":\"(c) IG, pege78\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/blog\\\/urlaub-freizeit\\\/bademoeglichkeiten-abseits-des-woerthersees\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"visitklagenfurt\",\"item\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/category\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Urlaub &amp; Freizeit\",\"item\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/category\\\/blog\\\/urlaub-freizeit\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Badem\u00f6glichkeiten abseits des W\u00f6rthersees\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/\",\"name\":\"visitklagenfurt\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#organization\",\"name\":\"Tourismus Region Klagenfurt am W\u00f6rthersee GmbH\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/DT_K_Klagenfurt_S_RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/DT_K_Klagenfurt_S_RGB.png\",\"width\":2082,\"height\":1511,\"caption\":\"Tourismus Region Klagenfurt am W\u00f6rthersee GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#\\\/schema\\\/person\\\/ff6e2ff5da4943f8ce5aa0eb7608c20a\",\"name\":\"Isabella Sch\u00f6ndorfer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/isabella_sch\u00f6ndorfer_autor.jpg\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/isabella_sch\u00f6ndorfer_autor.jpg\",\"contentUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/isabella_sch\u00f6ndorfer_autor.jpg\",\"caption\":\"Isabella Sch\u00f6ndorfer\"},\"description\":\"Ich bin Klagenfurt! Ich bin Bella Sch\u00f6n. Kein marketinggesteuerter Fake-Account. Denn hinter dem ehrlichen Alias stecken facettenreiche Geschichten \u00fcber meine Heimatstadt bella Klagenfurt. Immer mit dabei: eine Extraportion Geheimtipp. Geboren in der s\u00fcdlichsten Hauptstadt \u00d6sterreichs und aufgewachsen ganz normal am schillernden W\u00f6rthersee. Wie fast jeden K\u00e4rntner hat es auch mich f\u00fcr eine Zeit \u00fcber die Grenzen der Stadt, des Landes und tu felix Austria verschlagen. Doch nur, um eines Tages wieder zur\u00fcckzukehren. Denn nicht nur mit allen heimischen Wassern gewaschen, sondern auch im geliebten W\u00f6rthersee gebadet, habe ich vieles \u00fcber Klagenfurt zu erz\u00e4hlen und so manches Schmankerl f\u00fcr euch parat. Lasst euch ein auf unsere Br\u00e4uche, Sitten und das herzliche Gem\u00fct, das das urbane Klagenfurt so f\u00fcr uns alle zu bieten hat!\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/author\\\/isabella_schoendorfer\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Baden abseits des W\u00f6rthersees: Sattnitz, Kalmusbad, etc. | visitklagenfurt","description":"Tipps f\u00fcr Wasserratten abseits des W\u00f6rthersees. Wilde Einstiege und erfrischende Geheimtipps aus Klagenfurt. Abk\u00fchlung garantiert!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.visitklagenfurt.at\/de\/blog\/urlaub-freizeit\/bademoeglichkeiten-abseits-des-woerthersees\/","og_locale":"de_DE","og_type":"article","og_title":"Baden abseits des W\u00f6rthersees: Sattnitz, Kalmusbad, etc. | visitklagenfurt","og_description":"Tipps f\u00fcr Wasserratten abseits des W\u00f6rthersees. Wilde Einstiege und erfrischende Geheimtipps aus Klagenfurt. Abk\u00fchlung garantiert!","og_url":"https:\/\/www.visitklagenfurt.at\/de\/blog\/urlaub-freizeit\/bademoeglichkeiten-abseits-des-woerthersees\/","og_site_name":"visitklagenfurt","article_published_time":"2022-06-27T08:00:00+00:00","article_modified_time":"2022-08-17T13:24:50+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/06\/8f61fee22780f0f1781377f1cd7dc2ac.jpg","type":"image\/jpeg"}],"author":"Isabella Sch\u00f6ndorfer","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Isabella Sch\u00f6ndorfer","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/urlaub-freizeit\/bademoeglichkeiten-abseits-des-woerthersees\/#article","isPartOf":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/urlaub-freizeit\/bademoeglichkeiten-abseits-des-woerthersees\/"},"author":{"name":"Isabella Sch\u00f6ndorfer","@id":"https:\/\/www.visitklagenfurt.at\/de\/#\/schema\/person\/ff6e2ff5da4943f8ce5aa0eb7608c20a"},"headline":"Badem\u00f6glichkeiten abseits des W\u00f6rthersees","datePublished":"2022-06-27T08:00:00+00:00","dateModified":"2022-08-17T13:24:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/urlaub-freizeit\/bademoeglichkeiten-abseits-des-woerthersees\/"},"wordCount":1191,"publisher":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/#organization"},"image":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/urlaub-freizeit\/bademoeglichkeiten-abseits-des-woerthersees\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/06\/8f61fee22780f0f1781377f1cd7dc2ac.jpg","keywords":["Sommer"],"articleSection":["Urlaub &amp; Freizeit"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/urlaub-freizeit\/bademoeglichkeiten-abseits-des-woerthersees\/","url":"https:\/\/www.visitklagenfurt.at\/de\/blog\/urlaub-freizeit\/bademoeglichkeiten-abseits-des-woerthersees\/","name":"Baden abseits des W\u00f6rthersees: Sattnitz, Kalmusbad, etc. | visitklagenfurt","isPartOf":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/urlaub-freizeit\/bademoeglichkeiten-abseits-des-woerthersees\/#primaryimage"},"image":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/urlaub-freizeit\/bademoeglichkeiten-abseits-des-woerthersees\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/06\/8f61fee22780f0f1781377f1cd7dc2ac.jpg","datePublished":"2022-06-27T08:00:00+00:00","dateModified":"2022-08-17T13:24:50+00:00","description":"Tipps f\u00fcr Wasserratten abseits des W\u00f6rthersees. Wilde Einstiege und erfrischende Geheimtipps aus Klagenfurt. Abk\u00fchlung garantiert!","breadcrumb":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/urlaub-freizeit\/bademoeglichkeiten-abseits-des-woerthersees\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.visitklagenfurt.at\/de\/blog\/urlaub-freizeit\/bademoeglichkeiten-abseits-des-woerthersees\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/urlaub-freizeit\/bademoeglichkeiten-abseits-des-woerthersees\/#primaryimage","url":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/06\/8f61fee22780f0f1781377f1cd7dc2ac.jpg","contentUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/06\/8f61fee22780f0f1781377f1cd7dc2ac.jpg","width":1080,"height":720,"caption":"(c) IG, pege78"},{"@type":"BreadcrumbList","@id":"https:\/\/www.visitklagenfurt.at\/de\/blog\/urlaub-freizeit\/bademoeglichkeiten-abseits-des-woerthersees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"visitklagenfurt","item":"https:\/\/www.visitklagenfurt.at\/de\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.visitklagenfurt.at\/de\/category\/blog\/"},{"@type":"ListItem","position":3,"name":"Urlaub &amp; Freizeit","item":"https:\/\/www.visitklagenfurt.at\/de\/category\/blog\/urlaub-freizeit\/"},{"@type":"ListItem","position":4,"name":"Badem\u00f6glichkeiten abseits des W\u00f6rthersees"}]},{"@type":"WebSite","@id":"https:\/\/www.visitklagenfurt.at\/de\/#website","url":"https:\/\/www.visitklagenfurt.at\/de\/","name":"visitklagenfurt","description":"","publisher":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.visitklagenfurt.at\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.visitklagenfurt.at\/de\/#organization","name":"Tourismus Region Klagenfurt am W\u00f6rthersee GmbH","url":"https:\/\/www.visitklagenfurt.at\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.visitklagenfurt.at\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/03\/DT_K_Klagenfurt_S_RGB.png","contentUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/03\/DT_K_Klagenfurt_S_RGB.png","width":2082,"height":1511,"caption":"Tourismus Region Klagenfurt am W\u00f6rthersee GmbH"},"image":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.visitklagenfurt.at\/de\/#\/schema\/person\/ff6e2ff5da4943f8ce5aa0eb7608c20a","name":"Isabella Sch\u00f6ndorfer","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/07\/isabella_sch\u00f6ndorfer_autor.jpg","url":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/07\/isabella_sch\u00f6ndorfer_autor.jpg","contentUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2020\/07\/isabella_sch\u00f6ndorfer_autor.jpg","caption":"Isabella Sch\u00f6ndorfer"},"description":"Ich bin Klagenfurt! Ich bin Bella Sch\u00f6n. Kein marketinggesteuerter Fake-Account. Denn hinter dem ehrlichen Alias stecken facettenreiche Geschichten \u00fcber meine Heimatstadt bella Klagenfurt. Immer mit dabei: eine Extraportion Geheimtipp. Geboren in der s\u00fcdlichsten Hauptstadt \u00d6sterreichs und aufgewachsen ganz normal am schillernden W\u00f6rthersee. Wie fast jeden K\u00e4rntner hat es auch mich f\u00fcr eine Zeit \u00fcber die Grenzen der Stadt, des Landes und tu felix Austria verschlagen. Doch nur, um eines Tages wieder zur\u00fcckzukehren. Denn nicht nur mit allen heimischen Wassern gewaschen, sondern auch im geliebten W\u00f6rthersee gebadet, habe ich vieles \u00fcber Klagenfurt zu erz\u00e4hlen und so manches Schmankerl f\u00fcr euch parat. Lasst euch ein auf unsere Br\u00e4uche, Sitten und das herzliche Gem\u00fct, das das urbane Klagenfurt so f\u00fcr uns alle zu bieten hat!","url":"https:\/\/www.visitklagenfurt.at\/de\/author\/isabella_schoendorfer\/"}]}},"_links":{"self":[{"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/posts\/39187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/comments?post=39187"}],"version-history":[{"count":19,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/posts\/39187\/revisions"}],"predecessor-version":[{"id":39583,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/posts\/39187\/revisions\/39583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/media\/39195"}],"wp:attachment":[{"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/media?parent=39187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/categories?post=39187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/tags?post=39187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}