{"id":5517,"date":"2022-09-01T14:10:00","date_gmt":"2022-09-01T12:10:00","guid":{"rendered":"http:\/\/blog.visitklagenfurt.at\/?p=5517"},"modified":"2024-09-10T11:26:08","modified_gmt":"2024-09-10T09:26:08","slug":"wandern-am-kreuzbergl-in-klagenfurt","status":"publish","type":"post","link":"https:\/\/www.visitklagenfurt.at\/de\/sportlich-aktiv\/wandern\/wandern-am-kreuzbergl-in-klagenfurt\/","title":{"rendered":"Wandern am Kreuzbergl in Klagenfurt"},"content":{"rendered":"\n<p>Mitten aus der belebten Innenstadt Klagenfurts sind es nur wenige Minuten hinein ins <strong>Naherholungsgebiet <\/strong>voller Ruhe, Natur und Vogelgezwitscher. Wandert man vom Neuen Platz mit dem Lindwurmbrunnen Richtung Westen in die Radetzkystra\u00dfe und h\u00e4lt sich leicht n\u00f6rdlich, geht es schon bald hinauf auf das Kreuzbergl.<\/p>\n\n\n\n<p>Das Kreuzbergl zeichnet sich vor allem dadurch aus, dass es einen <strong>flie\u00dfenden \u00dcbergang von der Stadt in eine Art Parklandschaft<\/strong> und schlie\u00dflich in die Natur bildet. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1642\" height=\"1095\" data-id=\"11695\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/01\/kreuzbergl_ausblick_aussichtspunkt_c-derhandler_1-web.jpeg\" alt=\"Das Kreuzbergl als Aussichtsturm\" class=\"wp-image-11695\"\/><figcaption class=\"wp-element-caption\">(c) Wolfgang Handler<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-sternwarte-am-kreuzbergl\">Sternwarte am Kreuzbergl<\/h2>\n\n\n\n<p>Die weithin sichtbare <a href=\"http:\/\/www.sternwarte-klagenfurt.at\/\">Sternwarte<\/a>, mit ihrer imposanten Kuppel ist dabei ein guter Anhaltspunkt. 1965 auf einem, weit \u00e4lteren, steinernen Aussichtsturm errichtet, bietet sie aus der N\u00e4he einen interessanten Anblick und von ihrer <strong>Aussichtsplattform <\/strong>einen Rundblick auf ganz Klagenfurt. Abends werden hier zu gewissen Zeiten gef\u00fchrte Beobachtungen des Sternenhimmels angeboten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-kreuzberglkirche-mit-kreuzweg\">Kreuzberglkirche mit Kreuzweg<\/h2>\n\n\n\n<p>Ein anderer, guter Orientierungspunkt um aufs Kreuzbergl zu finden, ist die bereits vom Stadttheater aus sichtbare <a href=\"https:\/\/www.visitklagenfurt.at\/de\/entdecken-und-erleben\/sehenswertes\/319-kreuzberglkirche.html\">Kreuzberglkirche<\/a>, am Ende der Radetzkystra\u00dfe. Die 1742 geweihte Kalvarienbergkirche zeichnet sich vor allem durch ihren imposanten Kreuzweg aus. Es ist der <strong>ideale Start f\u00fcr eine Wanderung <\/strong>auf das Kreuzbergl. <\/p>\n\n\n\n<p>Das einzige Kreuz am Kreuzbergl findet man bereits hier, neben der Kirche inklusive einem sch\u00f6nen Stadtpanorama f\u00fcr ein Erinnerungsfoto. Ein echtes Gipfelkreuz blieb dem Kreuzbergl bisher verwehrt.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5096\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/02\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0186-1024x683.jpg\" alt=\"Paar mit Blick auf Kreuzberglkirche in Klagenfurt\" class=\"wp-image-5096\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/02\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0186-1024x683.jpg 1024w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/02\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0186-300x200.jpg 300w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/02\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0186-768x512.jpg 768w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/02\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0186.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">(c) Tine Steinthaler<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Anhaltspunkte zur Orientierung<\/h2>\n\n\n\n<p>Jede Seite des langgezogenen H\u00fcgelr\u00fcckens hat einen ganz besonderen Charakter. Man muss sich gar nicht im Vorhinein entscheiden, welchen Weg mant w\u00e4hlt, sondern kann dies w\u00e4hrend des Wanderns spontan tun. <\/p>\n\n\n\n<p>Die Orientierung f\u00e4llt trotzdem immer leicht. Das liegt einerseits an der <strong>ausgezeichneten Beschilderung <\/strong>mit realistischen Zeitangaben und andererseits daran, dass das Gebiet doch recht \u00fcberschaubar ist. <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Am Ostabhang des Kreuzbergls (Stadtseite) <\/strong>befinden sich die Parkanlagen mit den Teichen, die Kalvarienberganlage, der <a href=\"https:\/\/landesmuseum.ktn.gv.at\/standorte\/kbz\">botanische Garten<\/a> und das <a href=\"https:\/\/www.schweizerhaus.co.at\">Schweizerhaus<\/a> als kulinarische Anlaufstation und Unterkunft mit Blick \u00fcber die Stadt.<br><\/li>\n\n\n\n<li><strong>Der S\u00fcdabhang (Seeseite)<\/strong> ist gepr\u00e4gt von dichtem Wald und einem langsamen \u00dcbergang ins Villenviertel St. Martin. Hier lockt <a href=\"https:\/\/www.dermuth.at\">Der Dermuth<\/a> mit seiner exklusiven Sonnenterrasse, dem beliebten Restaurant und modern eingerichteten Zimmern.<br><\/li>\n\n\n\n<li><strong>Der Westabhang<\/strong> des Kreuzbergls besteht im Grunde aus der Zillh\u00f6he und ist das Ziel der meisten Kreuzberglwanderer. Einige B\u00e4nke und ein kleiner Pavillon laden dazu ein, hier den herrlichen Blick auf den W\u00f6rthersee zu genie\u00dfen und anschlie\u00dfend \u00fcber den <a href=\"https:\/\/www.visitklagenfurt.at\/de\/entdecken-und-erleben\/seeleben\/weingaerten.html\">Weingarten der Stadtwinzer<\/a> in die Ostbucht abzusteigen. Wer noch weiter wandern will, gelangt von hier auch auf den W\u00f6rthersee Rundwanderweg und auf den Falkenberg.<br><\/li>\n\n\n\n<li><strong>Im Norden <\/strong>erstreckt sich ein weitl\u00e4ufiges Wandergebiet mit dem Falkenberg und der Schleppe Alm bis hin zum Schloss Hallegg mit seiner Teichlandschaft. Im Norden bietet der herrlich versteckt gelegene <a href=\"http:\/\/www.waldwirt.co.at\">Waldwirt<\/a> und das <a href=\"https:\/\/www.visitklagenfurt.at\/de\/entdecken-und-erleben\/kulinarik\/gasthaus-falkenberg.html\">Gasthaus Falkenberg<\/a> allerlei Gaumenfreuden im historischen Ambiente von Schloss Falkenberg.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"6128\" src=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/02\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0136-1024x683.jpg\" alt=\"Wandern auf das Kreuzbergl (Zillh\u00f6he)\" class=\"wp-image-6128\" srcset=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/02\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0136-1024x683.jpg 1024w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/02\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0136-300x200.jpg 300w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/02\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0136-768x512.jpg 768w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/02\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0136-1536x1024.jpg 1536w, https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/02\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0136.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">(c) Tine Steinthaler<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-die-besten-wandertouren-am-kreuzbergl\">Die besten Wandertouren am Kreuzbergl<\/h2>\n\n\n\n<p>Wenn man die Wanderung lieber konkret planen m\u00f6chte, findet man hier die <a href=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/02\/Kreuzbergl_Wanderkarte.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">aktuellen Wanderkarte<\/a> und die wichtigsten Wege am Kreuzbergl.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Zillh\u00f6he<\/h3>\n\n\n\n<p>In rund<strong> 8,5 Kilometern und 122 H\u00f6henmetern<\/strong> erlebt man die ganze Vielfalt des Kreuzbergls. Startpunkt ist die Kreuzberglwiese beim mittleren Teich.<\/p>\n\n\n\n<script type=\"text\/javascript\" src=\"https:\/\/www.outdooractive.com\/de\/embed\/17261084\/js?mw=false&amp;usr=8gzwg&amp;key=USR-IAXZOWZ2-EMWGKPMP-4OSSP4YG\"><\/script>\n\n\n\n<h3 class=\"wp-block-heading\">2. Von der Stadt zum See<\/h3>\n\n\n\n<p>Oder soll es zum W\u00f6rthersee gehen? Dann starten man am besten mitten in der Stadt und wandert \u00fcber 9,2 Kilometer und 148 H\u00f6henmeter \u00fcbers Kreuzbergl bis zur W\u00f6rthersee Ostbucht.<\/p>\n\n\n\n<script type=\"text\/javascript\" src=\"https:\/\/www.outdooractive.com\/de\/embed\/15328408\/js?mw=false&amp;usr=8gzwg&amp;key=USR-IAXZOWZ2-EMWGKPMP-4OSSP4YG\"><\/script>\n\n\n\n<h3 class=\"wp-block-heading\">3. Falkenberg und Fliehburgh\u00f6he<\/h3>\n\n\n\n<p>Etwas knackiger ist der Anstieg von der W\u00f6rthersee Ostbucht \u00fcber die Zillh\u00f6he auf den Falkenberg und die Fliehburgh\u00f6he. Sie werden nach den 6,5 Kilometern und 237 H\u00f6henmetern daf\u00fcr aber mit einem kellerkalten Schleppebier direkt neben der Brauerei im <a href=\"https:\/\/www.schleppe-felsenkeller.at\">Felsenkeller<\/a> belohnt.<\/p>\n\n\n\n<script type=\"text\/javascript\" src=\"https:\/\/www.outdooractive.com\/de\/embed\/15328969\/js?mw=false&amp;usr=8gzwg&amp;key=USR-IAXZOWZ2-EMWGKPMP-4OSSP4YG\"><\/script>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In welcher Stadt kann man schon direkt vom Hauptplatz aus los wandern? In Klagenfurt geht das ganz locker am Kreuzbergl! Denn das Naherholungsgebiet ist auch eine beliebte und abwechslungsreiche Wandergegend. <\/p>\n","protected":false},"author":31,"featured_media":6125,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[186],"tags":[611,213],"class_list":["post-5517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wandern","tag-herbsturlaub","tag-wandern"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wandern am Kreuzbergl: Wanderwege &amp; Touren | visitklagenfurt<\/title>\n<meta name=\"description\" content=\"Wo kann man schon direkt vom Hauptplatz aus los wandern? In Klagenfurt geht das ganz locker am Kreuzbergl! Mehr zu den Wanderwegen hier!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.visitklagenfurt.at\/de\/sportlich-aktiv\/wandern\/wandern-am-kreuzbergl-in-klagenfurt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wandern am Kreuzbergl in Klagenfurt | visitklagenfurt\" \/>\n<meta property=\"og:description\" content=\"Wo kann man schon direkt vom Hauptplatz aus los wandern? In Klagenfurt geht das ganz locker am Kreuzbergl! Mehr zu den Wanderwegen hier!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visitklagenfurt.at\/de\/sportlich-aktiv\/wandern\/wandern-am-kreuzbergl-in-klagenfurt\/\" \/>\n<meta property=\"og:site_name\" content=\"visitklagenfurt\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-01T12:10:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-10T09:26:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/02\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0316.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"visitklagenfurt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"visitklagenfurt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/sportlich-aktiv\\\/wandern\\\/wandern-am-kreuzbergl-in-klagenfurt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/sportlich-aktiv\\\/wandern\\\/wandern-am-kreuzbergl-in-klagenfurt\\\/\"},\"author\":{\"name\":\"visitklagenfurt\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#\\\/schema\\\/person\\\/7bc1cce71726d48c458144f55517b2df\"},\"headline\":\"Wandern am Kreuzbergl in Klagenfurt\",\"datePublished\":\"2022-09-01T12:10:00+00:00\",\"dateModified\":\"2024-09-10T09:26:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/sportlich-aktiv\\\/wandern\\\/wandern-am-kreuzbergl-in-klagenfurt\\\/\"},\"wordCount\":590,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/sportlich-aktiv\\\/wandern\\\/wandern-am-kreuzbergl-in-klagenfurt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0316.jpg\",\"keywords\":[\"Herbsturlaub\",\"Wandern\"],\"articleSection\":[\"Wandern\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/sportlich-aktiv\\\/wandern\\\/wandern-am-kreuzbergl-in-klagenfurt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/sportlich-aktiv\\\/wandern\\\/wandern-am-kreuzbergl-in-klagenfurt\\\/\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/sportlich-aktiv\\\/wandern\\\/wandern-am-kreuzbergl-in-klagenfurt\\\/\",\"name\":\"Wandern am Kreuzbergl: Wanderwege & Touren | visitklagenfurt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/sportlich-aktiv\\\/wandern\\\/wandern-am-kreuzbergl-in-klagenfurt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/sportlich-aktiv\\\/wandern\\\/wandern-am-kreuzbergl-in-klagenfurt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0316.jpg\",\"datePublished\":\"2022-09-01T12:10:00+00:00\",\"dateModified\":\"2024-09-10T09:26:08+00:00\",\"description\":\"Wo kann man schon direkt vom Hauptplatz aus los wandern? In Klagenfurt geht das ganz locker am Kreuzbergl! Mehr zu den Wanderwegen hier!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/sportlich-aktiv\\\/wandern\\\/wandern-am-kreuzbergl-in-klagenfurt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/sportlich-aktiv\\\/wandern\\\/wandern-am-kreuzbergl-in-klagenfurt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/sportlich-aktiv\\\/wandern\\\/wandern-am-kreuzbergl-in-klagenfurt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0316.jpg\",\"contentUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0316.jpg\",\"width\":1600,\"height\":1067,\"caption\":\"(c) Tine Steinthaler\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/sportlich-aktiv\\\/wandern\\\/wandern-am-kreuzbergl-in-klagenfurt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"visitklagenfurt\",\"item\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sportlich-Aktiv\",\"item\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/category\\\/sportlich-aktiv\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wandern\",\"item\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/category\\\/sportlich-aktiv\\\/wandern\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Wandern am Kreuzbergl in Klagenfurt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/\",\"name\":\"visitklagenfurt\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#organization\",\"name\":\"Tourismus Region Klagenfurt am W\u00f6rthersee GmbH\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/DT_K_Klagenfurt_S_RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/DT_K_Klagenfurt_S_RGB.png\",\"width\":2082,\"height\":1511,\"caption\":\"Tourismus Region Klagenfurt am W\u00f6rthersee GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/#\\\/schema\\\/person\\\/7bc1cce71726d48c458144f55517b2df\",\"name\":\"visitklagenfurt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/KLU_LINDWURM_Blau.jpg\",\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/KLU_LINDWURM_Blau.jpg\",\"contentUrl\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/KLU_LINDWURM_Blau.jpg\",\"caption\":\"visitklagenfurt\"},\"url\":\"https:\\\/\\\/www.visitklagenfurt.at\\\/de\\\/author\\\/visitklagenfurt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wandern am Kreuzbergl: Wanderwege & Touren | visitklagenfurt","description":"Wo kann man schon direkt vom Hauptplatz aus los wandern? In Klagenfurt geht das ganz locker am Kreuzbergl! Mehr zu den Wanderwegen hier!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.visitklagenfurt.at\/de\/sportlich-aktiv\/wandern\/wandern-am-kreuzbergl-in-klagenfurt\/","og_locale":"de_DE","og_type":"article","og_title":"Wandern am Kreuzbergl in Klagenfurt | visitklagenfurt","og_description":"Wo kann man schon direkt vom Hauptplatz aus los wandern? In Klagenfurt geht das ganz locker am Kreuzbergl! Mehr zu den Wanderwegen hier!","og_url":"https:\/\/www.visitklagenfurt.at\/de\/sportlich-aktiv\/wandern\/wandern-am-kreuzbergl-in-klagenfurt\/","og_site_name":"visitklagenfurt","article_published_time":"2022-09-01T12:10:00+00:00","article_modified_time":"2024-09-10T09:26:08+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/02\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0316.jpg","type":"image\/jpeg"}],"author":"visitklagenfurt","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"visitklagenfurt","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.visitklagenfurt.at\/de\/sportlich-aktiv\/wandern\/wandern-am-kreuzbergl-in-klagenfurt\/#article","isPartOf":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/sportlich-aktiv\/wandern\/wandern-am-kreuzbergl-in-klagenfurt\/"},"author":{"name":"visitklagenfurt","@id":"https:\/\/www.visitklagenfurt.at\/de\/#\/schema\/person\/7bc1cce71726d48c458144f55517b2df"},"headline":"Wandern am Kreuzbergl in Klagenfurt","datePublished":"2022-09-01T12:10:00+00:00","dateModified":"2024-09-10T09:26:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/sportlich-aktiv\/wandern\/wandern-am-kreuzbergl-in-klagenfurt\/"},"wordCount":590,"commentCount":0,"publisher":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/#organization"},"image":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/sportlich-aktiv\/wandern\/wandern-am-kreuzbergl-in-klagenfurt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/02\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0316.jpg","keywords":["Herbsturlaub","Wandern"],"articleSection":["Wandern"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.visitklagenfurt.at\/de\/sportlich-aktiv\/wandern\/wandern-am-kreuzbergl-in-klagenfurt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.visitklagenfurt.at\/de\/sportlich-aktiv\/wandern\/wandern-am-kreuzbergl-in-klagenfurt\/","url":"https:\/\/www.visitklagenfurt.at\/de\/sportlich-aktiv\/wandern\/wandern-am-kreuzbergl-in-klagenfurt\/","name":"Wandern am Kreuzbergl: Wanderwege & Touren | visitklagenfurt","isPartOf":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/sportlich-aktiv\/wandern\/wandern-am-kreuzbergl-in-klagenfurt\/#primaryimage"},"image":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/sportlich-aktiv\/wandern\/wandern-am-kreuzbergl-in-klagenfurt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/02\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0316.jpg","datePublished":"2022-09-01T12:10:00+00:00","dateModified":"2024-09-10T09:26:08+00:00","description":"Wo kann man schon direkt vom Hauptplatz aus los wandern? In Klagenfurt geht das ganz locker am Kreuzbergl! Mehr zu den Wanderwegen hier!","breadcrumb":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/sportlich-aktiv\/wandern\/wandern-am-kreuzbergl-in-klagenfurt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.visitklagenfurt.at\/de\/sportlich-aktiv\/wandern\/wandern-am-kreuzbergl-in-klagenfurt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.visitklagenfurt.at\/de\/sportlich-aktiv\/wandern\/wandern-am-kreuzbergl-in-klagenfurt\/#primaryimage","url":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/02\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0316.jpg","contentUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/02\/KTR-Laufen-am-Kreuzbergl-2020-07-29_0316.jpg","width":1600,"height":1067,"caption":"(c) Tine Steinthaler"},{"@type":"BreadcrumbList","@id":"https:\/\/www.visitklagenfurt.at\/de\/sportlich-aktiv\/wandern\/wandern-am-kreuzbergl-in-klagenfurt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"visitklagenfurt","item":"https:\/\/www.visitklagenfurt.at\/de\/"},{"@type":"ListItem","position":2,"name":"Sportlich-Aktiv","item":"https:\/\/www.visitklagenfurt.at\/de\/category\/sportlich-aktiv\/"},{"@type":"ListItem","position":3,"name":"Wandern","item":"https:\/\/www.visitklagenfurt.at\/de\/category\/sportlich-aktiv\/wandern\/"},{"@type":"ListItem","position":4,"name":"Wandern am Kreuzbergl in Klagenfurt"}]},{"@type":"WebSite","@id":"https:\/\/www.visitklagenfurt.at\/de\/#website","url":"https:\/\/www.visitklagenfurt.at\/de\/","name":"visitklagenfurt","description":"","publisher":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.visitklagenfurt.at\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.visitklagenfurt.at\/de\/#organization","name":"Tourismus Region Klagenfurt am W\u00f6rthersee GmbH","url":"https:\/\/www.visitklagenfurt.at\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.visitklagenfurt.at\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/03\/DT_K_Klagenfurt_S_RGB.png","contentUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2022\/03\/DT_K_Klagenfurt_S_RGB.png","width":2082,"height":1511,"caption":"Tourismus Region Klagenfurt am W\u00f6rthersee GmbH"},"image":{"@id":"https:\/\/www.visitklagenfurt.at\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.visitklagenfurt.at\/de\/#\/schema\/person\/7bc1cce71726d48c458144f55517b2df","name":"visitklagenfurt","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/05\/KLU_LINDWURM_Blau.jpg","url":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/05\/KLU_LINDWURM_Blau.jpg","contentUrl":"https:\/\/www.visitklagenfurt.at\/wp-content\/uploads\/2021\/05\/KLU_LINDWURM_Blau.jpg","caption":"visitklagenfurt"},"url":"https:\/\/www.visitklagenfurt.at\/de\/author\/visitklagenfurt\/"}]}},"_links":{"self":[{"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/posts\/5517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/comments?post=5517"}],"version-history":[{"count":28,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/posts\/5517\/revisions"}],"predecessor-version":[{"id":70036,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/posts\/5517\/revisions\/70036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/media\/6125"}],"wp:attachment":[{"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/media?parent=5517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/categories?post=5517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.visitklagenfurt.at\/de\/wp-json\/wp\/v2\/tags?post=5517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}